{"id":6289,"date":"2022-09-16T17:14:46","date_gmt":"2022-09-16T17:14:46","guid":{"rendered":"https:\/\/fitolympia.com\/?p=6289"},"modified":"2022-09-16T17:14:47","modified_gmt":"2022-09-16T17:14:47","slug":"how-to-boost-stamina-naturally-post-lockdown-expert-reveals-5-easy-ways","status":"publish","type":"post","link":"https:\/\/fitolympia.com\/pt\/how-to-boost-stamina-naturally-post-lockdown-expert-reveals-5-easy-ways\/","title":{"rendered":"Como aumentar a resist\u00eancia naturalmente p\u00f3s-bloqueio especialista revela 5 maneiras f\u00e1ceis"},"content":{"rendered":"<h5 class=\"wp-block-heading\">Como estamos lentamente saindo de nossas casas, come\u00e7ando a ir para o escrit\u00f3rio, descobrimos que a resist\u00eancia para faz\u00ea-lo n\u00e3o est\u00e1 l\u00e1. \u00c9 hora de nos reconectarmos &#8211; s\u00f3 precisamos dar pequenos passos para chegar onde queremos estar e faz\u00ea-lo de forma sistem\u00e1tica.<\/h5> <p>Destaques<\/p> <ul class=\"wp-block-list\"><li>Boost stamina post lockdown: Take small steps to reach back<\/li><li>Eating at regular hours means the energy levels remain steady<\/li><li>Nuts add healthy fats, fibre, protein and most importantly, antioxidants<\/li><\/ul> <p>&#8216;COVID-19&#8217; e &#8216;stay in home&#8217; s\u00e3o algumas das palavras mais tend\u00eancias desde os \u00faltimos tr\u00eas meses. A pandemia cont\u00ednua fez severas mudan\u00e7as em nosso estilo de vida, afetando indiretamente nosso bem-estar f\u00edsico e psicol\u00f3gico. Passamos do trabalho do escrit\u00f3rio para as nossas mesas de casa, de jantar em restaurantes para apenas comer em casa, de ir \u00e0 academia diariamente para realizar tarefas dom\u00e9sticas di\u00e1rias &#8211; nossas vidas s\u00e3o religadas e nossos movimentos s\u00e3o restritos. Embora existam muitos que encontraram uma maneira de se exercitar diariamente e manter um padr\u00e3o alimentar saud\u00e1vel, mas para a maioria de n\u00f3s era apenas sentar, comer todas as deliciosas e decadentes guloseimas caseiras, que est\u00e1vamos perdendo por causa da correria da vida di\u00e1ria.<br\/><\/p> <p>Hoje, como estamos lentamente saindo de nossas casas, come\u00e7ando a ir para o escrit\u00f3rio, descobrimos que a for\u00e7a para faz\u00ea-lo n\u00e3o est\u00e1 l\u00e1. N\u00f3s nos cansamos facilmente e sentimos a necessidade de nos esfor\u00e7ar mentalmente e fisicamente para fazer o que costum\u00e1vamos fazer sem fazer esfor\u00e7o extra. Mas n\u00e3o se preocupe! \u00c9 hora de nos reconectarmos &#8211; s\u00f3 precisamos dar pequenos passos para chegar onde queremos estar e faz\u00ea-lo de forma sistem\u00e1tica.<\/p> <p><\/p> <figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/c.ndtvimg.com\/2020-04\/eksv60jo_work-from-home-diet-tips_625x300_06_April_20.jpg\" alt=\"eksv60jo\"\/><\/figure> <p><em><sup>Boost stamina post lockdown: Take small steps to reach back.<\/sup><\/em><\/p> <h2 class=\"wp-block-heading\"><br\/>Aqui est\u00e3o maneiras f\u00e1ceis de aumentar seu bloqueio p\u00f3s-resist\u00eancia:<\/h2> <h3 class=\"wp-block-heading\"><br\/>Coma em hor\u00e1rios apropriados<\/h3> <p>Faz uma diferen\u00e7a para o nosso sistema que est\u00e1 intimamente ligado ao rel\u00f3gio solar. Defina seus hor\u00e1rios de refei\u00e7\u00e3o e mantenha-os mantendo uma margem de manobra de 30 minutos para cima ou para baixo. Comer em horas regulares significa que os n\u00edveis de energia permanecem est\u00e1veis e n\u00e3o oscilam de altos a baixos. Isso ajudar\u00e1 seu ritmo corporal a se estabelecer; ele vai equilibrar os horm\u00f4nios, mantendo voc\u00ea energizado.<br\/><\/p> <figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/c.ndtvimg.com\/2018-10\/a8ikifr8_intermittent-fasting-for-weight-loss_625x300_22_October_18.jpg\" alt=\"a8ikifr8\"\/><\/figure> <p><em><sup>Eating at regular hours means the energy levels remain steady.<\/sup><\/em><br\/><\/p> <h3 class=\"wp-block-heading\"><br\/>Coma alimentos ricos em nutrientes<\/h3> <p>Uma das melhores coisas que aconteceu durante o confinamento foi que est\u00e1vamos comendo comida caseira fresca com ingredientes mais frescos. Aprendemos a fazer pizzas e hamb\u00fargueres em casa, mas todos com ingredientes frescos e saud\u00e1veis. Qualquer alimento mais pr\u00f3ximo de sua forma natural, menos processado e sazonal \u00e9 o melhor para sua sa\u00fade. As refei\u00e7\u00f5es de trapa\u00e7a s\u00e3o apenas 1-2 refei\u00e7\u00f5es por semana. Alimentos ricos em nutrientes adicionam sa\u00fade enquanto alimentos processados e refinados adicionam calorias vazias deixando voc\u00ea sem energia e se sentindo baixo. Alimentos fermentados adicionam boas bact\u00e9rias que mant\u00eam nosso intestino saud\u00e1vel e a absor\u00e7\u00e3o de nutrientes eficientes.<\/p> <p><\/p> <figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/c.ndtvimg.com\/2020-05\/sv35csg8_healthy-food_625x300_28_May_20.jpg\" alt=\"sv35csg8\"\/><\/figure> <p><sup><em>Any food that is closest to its natural form, least processed and seasonal is the best for your health.<\/em><\/sup><br\/><br\/>Beber, beber e beber muita \u00e1gua<\/p> <p>Estamos no meio dos ver\u00f5es e precisamos de hidrata\u00e7\u00e3o. Mesmo uma leve desidrata\u00e7\u00e3o nos deixa exaustos; portanto, deve-se tomar fluidos adequados, e um copo de \u00e1gua simples \u00e9 a melhor op\u00e7\u00e3o. Mas se apenas ter \u00e1gua \u00e9 mon\u00f3tono, voc\u00ea pode ter \u00e1gua fresca de lim\u00e3o, \u00e1gua de coco, ch\u00e1 gelado fresco, jaljeera ou aam panna sem a\u00e7\u00facar ou com a quantidade m\u00ednima de a\u00e7\u00facar. Bael Sherbet \u00e9 outra bebida incr\u00edvel que voc\u00ea pode experimentar. Novamente ao redescobrir a comida, tenho certeza que voc\u00ea deve ter encontrado um monte de bebidas tradicionais de ver\u00e3o que precisam de muito pouco trabalho e s\u00e3o super hidratantes. Mas mantenha a cafe\u00edna ao m\u00ednimo!<\/p> <figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/c.ndtvimg.com\/2019-04\/2isg0fk_pineapple-coconut-water_625x300_03_April_19.jpg\" alt=\"2isg0fk\"\/><\/figure> <p><sup><em>Have fresh lemon water, coconut water, fresh iced tea, jaljeera or aam panna but without sugar.<\/em><\/sup><br\/><br\/>Inclua nozes e sementes em sua dieta<\/p> <p>Nuts and seeds are a Yes in summers too. You can soak them if you believe they are &#8220;garam&#8221; in summers. You can even add nuts to your summer drinks. Almond thandai is a healthy drink and you can even have it in summers. We just need one ounce of nuts and seeds per day &#8211; meaning 15-20 almonds, one walnut and a teaspoon of seeds. Nuts add healthy fats, fibre, protein and most importantly, antioxidants, which are known to clean up the free radicals from our system. They are great for boosting immunity to.<br\/><\/p> <figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/c.ndtvimg.com\/2020-06\/3kic9bc_nuts_625x300_10_June_20.jpg\" alt=\"3kic9bc\"\/><\/figure> <p><sup><em>Nuts add healthy fats, fibre, protein and most importantly, antioxidants.<\/em><\/sup><br\/><\/p> <h3 class=\"wp-block-heading\"><br\/>Volte a se exercitar<\/h3> <p>Os que levaram esse tempo para n\u00e3o fazer nada no espa\u00e7o de exerc\u00edcios, precisam recome\u00e7ar. N\u00e3o importa onde voc\u00ea estava quando o confinamento aconteceu, voc\u00ea precisa come\u00e7ar tudo de novo. N\u00e3o volte ao alto n\u00edvel de exerc\u00edcio imediatamente &#8211; chegar l\u00e1 lentamente. E os que mantiveram um n\u00edvel m\u00e9dio de exerc\u00edcio, podem ir para o pr\u00f3ximo n\u00edvel, mas gradualmente.<br\/><\/p> <figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/c.ndtvimg.com\/2020-05\/vp6p2rk8_exercise_625x300_18_May_20.jpg\" alt=\"vp6p2rk8\"\/><\/figure> <p><sup><em>While exercising at home keep all distractions away.<\/em><\/sup><\/p> <p>Estes s\u00e3o tempos de teste e, embora muito esteja desbloqueando, o contato social m\u00ednimo ainda deve ser mantido, juntamente com a lavagem e higieniza\u00e7\u00e3o frequentes das m\u00e3os. Vamos recuperar nossas vidas, mas os bons h\u00e1bitos que fomos for\u00e7ados a reaprender como ter comida caseira, redescobrir alimentos tradicionais, higiene das m\u00e3os e corpos, passar tempo de qualidade com a fam\u00edlia e ficar parados por um tempo, n\u00e3o devem ser esquecidos. H\u00e1 um lado bom em cada nuvem e o sol brilha depois de cada noite escura.<br\/><\/p> <h4 class=\"wp-block-heading\">Fique seguro, fique saud\u00e1vel e volte para a zona!<\/h4> ","protected":false},"excerpt":{"rendered":"<p>Como estamos lentamente saindo de nossas casas, come\u00e7ando a ir para o escrit\u00f3rio, descobrimos que a resist\u00eancia para faz\u00ea-lo n\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[17],"tags":[23],"class_list":["post-6289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-health","tag-health"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"pt","enabled_languages":["en","es","de","fr","ru","hi","ar","tr","it","pt","na"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"na":{"title":false,"content":false,"excerpt":false}}},"featured_img":"https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/09\/running.jpg","categories_details":[{"id":17,"name":"Health","count":260,"parent":0}],"tags_details":[{"id":23,"name":"Health","count":32,"parent":0}],"comment_count":0,"author_name":"Staff","author_img":"https:\/\/secure.gravatar.com\/avatar\/0770ff71d5267ad67c1cefbf36008dc2a2753c332616ff451380094010b0d281?s=96&d=mm&r=g","post_views":1811,"_links":{"self":[{"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/posts\/6289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/comments?post=6289"}],"version-history":[{"count":10,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/posts\/6289\/revisions"}],"predecessor-version":[{"id":17248,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/posts\/6289\/revisions\/17248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/media\/6290"}],"wp:attachment":[{"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/media?parent=6289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/categories?post=6289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/tags?post=6289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}