{"id":14223,"date":"2024-06-20T00:00:05","date_gmt":"2024-06-20T00:00:05","guid":{"rendered":"https:\/\/fitolympia.com\/?p=14223"},"modified":"2024-06-20T15:37:09","modified_gmt":"2024-06-20T15:37:09","slug":"alkaline-water-benefits-and-risks","status":"publish","type":"post","link":"https:\/\/fitolympia.com\/pt\/alkaline-water-benefits-and-risks\/","title":{"rendered":"\u00c1GUA ALCALINA: BENEF\u00cdCIOS E RISCOS"},"content":{"rendered":"<\/p>\n<p><strong>O que \u00e9 \u00e1gua alcalina?<\/strong><\/p>\n<p>Voc\u00ea deve ter ouvido v\u00e1rias alega\u00e7\u00f5es de sa\u00fade sobre \u00e1gua alcalina. Alguns dizem que pode ajudar a retardar o processo de envelhecimento, regular o n\u00edvel de pH do seu corpo e prevenir doen\u00e7as cr\u00f4nicas como o c\u00e2ncer. Mas o que exatamente \u00e9 \u00e1gua alcalina, e por que todo o hype?<\/p>\n<p>A &#8220;alcalina&#8221; na \u00e1gua alcalina refere-se ao seu n\u00edvel de pH. O n\u00edvel de pH \u00e9 um n\u00famero que mede o qu\u00e3o \u00e1cida ou alcalina uma subst\u00e2ncia \u00e9 em uma escala de 0 a 14. Por exemplo, algo com um pH de 1 seria muito \u00e1cido e algo com um pH de 13 seria muito alcalino.<\/p>\n<p>A \u00e1gua alcalina tem um n\u00edvel de pH mais alto do que a \u00e1gua pot\u00e1vel normal. Por causa disso, alguns defensores da \u00e1gua alcalina acreditam que pode neutralizar o \u00e1cido em seu corpo.<\/p>\n<p>A \u00e1gua pot\u00e1vel normal geralmente tem um pH neutro de 7. A \u00e1gua alcalina normalmente tem um pH de 8 ou 9. No entanto, o pH sozinho n\u00e3o \u00e9 suficiente para transmitir alcalinidade substancial \u00e0 \u00e1gua.<\/p>\n<p>A \u00e1gua alcalina tamb\u00e9m deve conter minerais alcalinos e potencial de redu\u00e7\u00e3o de oxida\u00e7\u00e3o negativa (ORP). ORP \u00e9 a capacidade da \u00e1gua de agir como um pr\u00f3 ou antioxidante. Quanto mais negativo o valor orp, mais antioxidizador \u00e9.<\/p>\n<h2><a>Funciona mesmo?<\/a><\/h2>\n<p>A \u00e1gua alcalina \u00e9 um pouco controversa. Muitos profissionais de sa\u00fade dizem que n\u00e3o h\u00e1 pesquisas suficientes para apoiar as muitas reivindica\u00e7\u00f5es de sa\u00fade feitas por usu\u00e1rios e vendedores. Diferen\u00e7as nos achados da pesquisa podem estar relacionadas aos tipos de estudos alcalinos de \u00e1gua.<\/p>\n<p>De acordo com a\u00a0<a href=\"https:\/\/www.mayoclinic.org\/healthy-living\/nutrition-and-healthy-eating\/expert-answers\/alkaline-water\/faq-20058029\" target=\"_blank\" rel=\"noreferrer noopener\">Cl\u00ednica Mayo,<\/a>a \u00e1gua regular \u00e9 melhor para a maioria das pessoas. Eles afirmam que n\u00e3o h\u00e1 evid\u00eancias cient\u00edficas que verifiquem totalmente as alega\u00e7\u00f5es feitas pelos partid\u00e1rios da \u00e1gua alcalina.<\/p>\n<p>No entanto, existem alguns estudos que sugerem que a \u00e1gua alcalina pode ser \u00fatil para certas condi\u00e7\u00f5es.<\/p>\n<p>Por exemplo, um\u00a0<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/22844861\" target=\"_blank\" rel=\"noreferrer noopener\">estudo de 2012\u00a0<\/a>descobriu que beber \u00e1gua alcalina naturalmente carbonada com um pH de 8,8 pode ajudar a desativar a pepsina, a principal enzima que causa\u00a0<strong>o refluxo \u00e1cido.<\/strong><\/p>\n<p>Outro\u00a0<a href=\"http:\/\/en.cnki.com.cn\/Article_en\/CJFDTOTAL-SHYI200112005.htm\" target=\"_blank\" rel=\"noreferrer noopener\">estudo<\/a>\u00a0sugeriu que beber \u00e1gua ionizada alcalina pode ter benef\u00edcios para pessoas com\u00a0<strong>press\u00e3o alta,<\/strong>\u00a0<strong>diabetes<\/strong>e\u00a0<strong>colesterol alto.<\/strong><\/p>\n<p>Um\u00a0<a href=\"https:\/\/jissn.biomedcentral.com\/articles\/10.1186\/s12970-016-0153-8\" target=\"_blank\" rel=\"noreferrer noopener\">estudo mais recente<\/a>\u00a0que incluiu 100 pessoas encontrou uma diferen\u00e7a significativa na viscosidade sangu\u00ednea total depois de consumir \u00e1gua de alto pH em compara\u00e7\u00e3o com a \u00e1gua regular ap\u00f3s um treino extenuante. Viscosidade \u00e9 a medi\u00e7\u00e3o direta de como o sangue flui eficientemente atrav\u00e9s dos vasos.<\/p>\n<p>Aqueles que consumiram \u00e1gua de alto pH reduziram a viscosidade em 6,3% em compara\u00e7\u00e3o com 3,36% com \u00e1gua pot\u00e1vel purificada padr\u00e3o. Isso significa que o sangue fluiu mais eficientemente com \u00e1gua alcalina. Isso pode aumentar a entrega de oxig\u00eanio em todo o corpo.<\/p>\n<p>No entanto, mais pesquisas s\u00e3o necess\u00e1rias al\u00e9m desses pequenos estudos. Em particular, pesquisas s\u00e3o necess\u00e1rias para responder a outras reivindica\u00e7\u00f5es feitas por apoiadores alcalinos da \u00e1gua.<\/p>\n<p>Apesar da falta de pesquisas cient\u00edficas comprovadas, os defensores da \u00e1gua alcalina ainda acreditam em seus benef\u00edcios propostos para a sa\u00fade. Estes incluem:<\/p>\n<ul>\n<li>propriedades anti-envelhecimento (atrav\u00e9s de antioxidantes l\u00edquidos que absorvem mais rapidamente no corpo humano)<\/li>\n<li>propriedades de limpeza de c\u00f3lon<\/li>\n<li>suporte ao sistema imunol\u00f3gico<\/li>\n<li>hidrata\u00e7\u00e3o, sa\u00fade da pele e outras propriedades desintoxicantes<\/li>\n<li>perda de peso<\/li>\n<li>resist\u00eancia ao c\u00e2ncer<\/li>\n<\/ul>\n<p>Eles tamb\u00e9m argumentam que os refrigerantes, que s\u00e3o notoriamente \u00e1cidos, t\u00eam ORPs muito positivos levando a muitos problemas de sa\u00fade, enquanto \u00e1guas adequadamente ionizadas e alcalinizadas t\u00eam ORPs altamente negativos. O ch\u00e1 verde \u00e9 rico em antioxidantes e tem um ORP ligeiramente negativo.<\/p>\n<h2><a>Poss\u00edveis efeitos colaterais e riscos da \u00e1gua alcalina<\/a><\/h2>\n<p>Embora a \u00e1gua pot\u00e1vel alcalina seja considerada segura, pode produzir efeitos colaterais negativos.<\/p>\n<p>Alguns exemplos de efeitos colaterais negativos incluem a redu\u00e7\u00e3o da acidez estomacal natural, que ajuda a matar bact\u00e9rias e expulsar outros pat\u00f3genos indesej\u00e1veis de entrar em sua corrente sangu\u00ednea.<\/p>\n<p>Al\u00e9m disso, um excesso global de alcalinidade no corpo pode causar problemas gastrointestinais e irrita\u00e7\u00f5es na pele. A alcalinidade demais tamb\u00e9m pode agitar o pH normal do corpo, levando \u00e0 alcalose metab\u00f3lica, condi\u00e7\u00e3o que pode produzir os seguintes sintomas:<\/p>\n<ul>\n<li>N\u00e1usea<\/li>\n<li>v\u00f3mito<\/li>\n<li>tremores de m\u00e3o<\/li>\n<li>contra\u00e7\u00e3o muscular<\/li>\n<li>formigamento nas extremidades ou rosto<\/li>\n<li>confus\u00e3o<\/li>\n<\/ul>\n<p>A alcalose tamb\u00e9m pode causar uma diminui\u00e7\u00e3o do c\u00e1lcio livre no organismo, o que pode afetar a sa\u00fade \u00f3ssea. No entanto, a causa mais comum de hipocalcemia n\u00e3o \u00e9 de beber \u00e1gua alcalina, mas de ter uma gl\u00e2ndula paratireoide subativa.<\/p>\n<h2><a>Natural ou artificial?<\/a><\/h2>\n<p>A \u00e1gua naturalmente alcalina ocorre quando a \u00e1gua passa sobre rochas &#8211; como nascentes &#8211; e capta minerais, que aumentam seu n\u00edvel alcalino.<\/p>\n<p>No entanto, muitas pessoas que bebem \u00e1gua alcalina compram \u00e1gua alcalina que passou por um processo qu\u00edmico chamado eletr\u00f3lise.<\/p>\n<p>Esta t\u00e9cnica usa um produto chamado ionizador para elevar o pH da \u00e1gua normal. Fabricantes de ionizadores dizem que a eletricidade \u00e9 usada para separar mol\u00e9culas na \u00e1gua que s\u00e3o mais \u00e1cidas ou mais alcalinas. A \u00e1gua \u00e1cida \u00e9 ent\u00e3o funneled para fora.<\/p>\n<p>Ainda assim, alguns m\u00e9dicos e pesquisadores dizem que essas alega\u00e7\u00f5es n\u00e3o s\u00e3o apoiadas por pesquisas de qualidade. A qualidade da \u00e1gua da fonte original, antes da ioniza\u00e7\u00e3o, \u00e9 crucial para garantir que os contaminantes n\u00e3o estejam presentes na \u00e1gua pot\u00e1vel.<\/p>\n<p>Alguns cientistas aconselham o uso de osmose reversa para purificar adequadamente a \u00e1gua antes de conectar um ionizador alcalino, que pode elevar o pH e adicionar minerais.<\/p>\n<p>Um estudo publicado pela\u00a0<a href=\"http:\/\/www.who.int\/water_sanitation_health\/dwq\/nutrientschap12.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Organiza\u00e7\u00e3o Mundial<\/a>\u00a0da Sa\u00fade alerta para a \u00e1gua pot\u00e1vel com baixo teor mineral, que \u00e9 criada por osmose reversa, destila\u00e7\u00e3o e outros m\u00e9todos (sem mineraliza\u00e7\u00e3o adicional) regularmente.<\/p>\n<h2><a>Onde voc\u00ea consegue isso?<\/a><\/h2>\n<p>A \u00e1gua alcalina pode ser comprada em muitas mercearias ou lojas de alimentos saud\u00e1veis. Tamb\u00e9m pode ser encontrado online.<\/p>\n<p>Os ionizadores de \u00e1gua tamb\u00e9m s\u00e3o vendidos em muitas grandes lojas da rede.<\/p>\n<p>Voc\u00ea tamb\u00e9m pode fazer o seu pr\u00f3prio em casa. Embora os sucos de lim\u00e3o e lim\u00e3o sejam \u00e1cidos, eles cont\u00eam minerais que podem criar subprodutos alcalinos uma vez digeridos e metabolizados. Adicionar um aperto de lim\u00e3o ou lim\u00e3o a um copo de \u00e1gua pode tornar sua \u00e1gua mais alcalina \u00e0 medida que seu corpo o digere. Adicionar gotas de pH ou bicarbonato de s\u00f3dio \u00e9 outra maneira de tornar a \u00e1gua mais alcalina.<\/p>\n<p>Se a \u00e1gua for filtrada adequadamente para remover contaminantes, ionizadas e reminenizadas, ou compradas de uma fonte de qualidade, n\u00e3o h\u00e1 evid\u00eancias que sugiram uma limita\u00e7\u00e3o sobre a quantidade de \u00e1gua alcalina que pode ser consumida diariamente.<\/p>\n<h2><a>\u00c9 seguro?<\/a><\/h2>\n<p>A quest\u00e3o que muitos profissionais de sa\u00fade t\u00eam com \u00e1gua alcalina n\u00e3o \u00e9 a sua seguran\u00e7a, mas sim as alega\u00e7\u00f5es de sa\u00fade que s\u00e3o feitas sobre ela.<\/p>\n<p>N\u00e3o h\u00e1 evid\u00eancias cient\u00edficas suficientes para apoiar o uso de \u00e1gua alcalina como tratamento para qualquer condi\u00e7\u00e3o de sa\u00fade. Especialistas m\u00e9dicos alertam para n\u00e3o acreditar em todas as alega\u00e7\u00f5es de marketing.<\/p>\n<p>Beber \u00e1gua alcalina natural \u00e9 geralmente considerado seguro, uma vez que cont\u00e9m minerais naturais.<\/p>\n<p>No entanto, voc\u00ea deve ter cuidado com \u00e1gua alcalina artificial, que provavelmente cont\u00e9m menos minerais bons do que seu pH alto faria voc\u00ea acreditar, e pode conter contaminantes. Lembre-se tamb\u00e9m, beber muita \u00e1gua alcalina pode deix\u00e1-lo deficiente em minerais.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>O que \u00e9 \u00e1gua alcalina? Voc\u00ea deve ter ouvido v\u00e1rias alega\u00e7\u00f5es de sa\u00fade sobre \u00e1gua alcalina. Alguns dizem que pode [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[54,202],"tags":[],"class_list":["post-14223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-benefits"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"pt","enabled_languages":["en","es","de","fr","ru","hi","ar","tr","it","pt","na"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"na":{"title":false,"content":false,"excerpt":false}}},"featured_img":"https:\/\/fitolympia.com\/wp-content\/uploads\/2021\/07\/AlkalineWaterMenuLabel.jpg","categories_details":[{"id":54,"name":"General","count":105,"parent":0},{"id":202,"name":"Benefits","count":165,"parent":0}],"tags_details":[],"comment_count":0,"author_name":"Staff","author_img":"https:\/\/secure.gravatar.com\/avatar\/0770ff71d5267ad67c1cefbf36008dc2a2753c332616ff451380094010b0d281?s=96&d=mm&r=g","post_views":6445,"_links":{"self":[{"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/posts\/14223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/comments?post=14223"}],"version-history":[{"count":10,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/posts\/14223\/revisions"}],"predecessor-version":[{"id":14264,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/posts\/14223\/revisions\/14264"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/media\/14224"}],"wp:attachment":[{"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/media?parent=14223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/categories?post=14223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fitolympia.com\/pt\/wp-json\/wp\/v2\/tags?post=14223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}