{"id":15393,"date":"2024-09-26T00:00:24","date_gmt":"2024-09-26T00:00:24","guid":{"rendered":"https:\/\/fitolympia.com\/?p=15393"},"modified":"2024-09-26T17:07:31","modified_gmt":"2024-09-26T17:07:31","slug":"urinary-tract-infection-how-to-prevent-while-travelling","status":"publish","type":"post","link":"https:\/\/fitolympia.com\/it\/urinary-tract-infection-how-to-prevent-while-travelling\/","title":{"rendered":"INFEZIONE DEL TRATTO URINARIO: COME PREVENIRE DURANTE IL VIAGGIO?"},"content":{"rendered":"\n<p>Un&#8217;infezione del sistema urinario, in cui i batteri nocivi entrano nelle urine dall&#8217;esterno del corpo, causando infezione e infiammazione, \u00e8 chiamata infezione del tratto urinario o UTI. La maggior parte delle donne sapr\u00e0 di cosa stiamo parlando in quanto colpisce il 50% delle donne, e, una volta che l&#8217;hai avuto, la probabilit\u00e0 che si ripeta \u00e8 pi\u00f9 alta.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.news-medical.net\/image.axd?picture=2021%2F3%2Fshutterstock_1827079931.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>&#8220;Il colpevole pi\u00f9 comune di UTI \u00e8 E.coli seguito da Klebsiella e Proteus. Di solito comporta un&#8217;infezione nella vescica urinaria. Le donne sperimentano l&#8217;infezione pi\u00f9 degli uomini poich\u00e9 l&#8217;uretra femminile \u00e8 pi\u00f9 corta e l&#8217;ano \u00e8 nelle immediate vicinanze. Quindi l&#8217;infezione ascendente \u00e8 la solita via per ottenere l&#8217;infezione. Nei maschi i batteri risiedono all&#8217;interno del corpo, di solito la ghiandola prostatica, e dentro e fuori d\u00e0 origine a UTI sintomatica&#8221;, spiega il Dott. Harish Bhat N, Clinical Lead, Urology, MGM Healthcare, Chennai. Pi\u00f9 tempo si trascorre viaggia su strada, maggiori sono le possibilit\u00e0 di contrarre l&#8217;UTI. Lunghi viaggi in auto o in autobus, servizi igienici impuri, scarsa igiene di manutenzione, sistema immunitario indebolito, salto dell&#8217;assunzione di acqua soprattutto durante il viaggio contribuiscono tutti all&#8217;infezione.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/femina.wwmindia.com\/content\/2021\/aug\/travel-021628828268.jpg\" alt=\"travel\"\/><\/figure>\n\n\n\n<p>Segnali di<br>avvertimento &#8220;Una sensazione di bruciore durante il passaggio dell&#8217;urina, aumento della frequenza urinaria e dell&#8217;urgenza, tracce di sangue nelle urine, cattivo odore sono alcuni dei sintomi comuni a cui fare attenzione&#8221;, afferma il dott. Bhat, che aggiunge che febbre e dolore loin di solito indicano un&#8217;UTI complicata che probabilmente coinvolge il rene.\u00c8 una sfida trovare servizi igienici puliti, specialmente durante i viaggi su strada in citt\u00e0 sconosciute, ma cerca di non tenere per tutto il tempo in cui questo aiuta a prevenire e curare l&#8217;infezione. &#8220;Una corretta igiene personale, lavarsi mani e genitali prima e dopo la minzione, il passaggio regolare delle urine ogni quattro ore, evitare stitichezza, assunzione liberale di acqua, lavaggio dell&#8217;ano, frequente cambiamento di tovaglioli sanitari, passaggio di urina e lavaggio prima e post rapporto sessuale sono poche misure preventive&#8221;, suggerisce il dott. Bhat. Consiglia un intervento medico immediato il prima per prevenire lo sviluppo di ulteriori complicazioni.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/femina.wwmindia.com\/content\/2021\/aug\/travel-031628828255.jpg\" alt=\"travel\"\/><\/figure>\n\n\n\n<p><br>Tienilo a portata di<br>mano 1. Bere acqua, acqua e pi\u00f9 acqua per sciacquare i batteri dal sistema.<br><br>2. Bere succhi freschi e tenera noce di cocco durante il viaggio aiuta a raffreddare il tuo corpo.<br><br>3. Il succo di mirtillo rosso \u00e8 stato trovato in alcuni studi per aiutare a ridurre la recidiva dell&#8217;UTI.<br><br>4. Colpisci la farmacia prima di viaggiare e tieni a portata di mano gli antibiotici prescritti dal medico.<br><br>5. Urinare immediatamente dopo il rapporto sessuale.<br><br>6. Utilizzare spray igienizzante per i servizi igienici durante l&#8217;utilizzo di strutture in citt\u00e0 e centri commerciali sconosciuti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un&#8217;infezione del sistema urinario, in cui i batteri nocivi entrano nelle urine dall&#8217;esterno del corpo, causando infezione e infiammazione, \u00e8 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[17,59],"tags":[],"class_list":["post-15393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-health","category-wellness"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"it","enabled_languages":["en","es","de","fr","ru","hi","ar","tr","it","pt","na"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"na":{"title":false,"content":false,"excerpt":false}}},"featured_img":"https:\/\/cdn.fitolympia.com\/file\/olympia-cdn\/wp-content\/uploads\/2021\/08\/travel-011628828296.jpg","categories_details":[{"id":17,"name":"Health","count":262,"parent":0},{"id":59,"name":"Wellness","count":79,"parent":0}],"tags_details":[],"comment_count":0,"author_name":"Staff","author_img":"https:\/\/secure.gravatar.com\/avatar\/0770ff71d5267ad67c1cefbf36008dc2a2753c332616ff451380094010b0d281?s=96&d=mm&r=g","post_views":5813,"_links":{"self":[{"href":"https:\/\/fitolympia.com\/it\/wp-json\/wp\/v2\/posts\/15393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitolympia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fitolympia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/it\/wp-json\/wp\/v2\/comments?post=15393"}],"version-history":[{"count":10,"href":"https:\/\/fitolympia.com\/it\/wp-json\/wp\/v2\/posts\/15393\/revisions"}],"predecessor-version":[{"id":15443,"href":"https:\/\/fitolympia.com\/it\/wp-json\/wp\/v2\/posts\/15393\/revisions\/15443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/it\/wp-json\/wp\/v2\/media\/15394"}],"wp:attachment":[{"href":"https:\/\/fitolympia.com\/it\/wp-json\/wp\/v2\/media?parent=15393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fitolympia.com\/it\/wp-json\/wp\/v2\/categories?post=15393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fitolympia.com\/it\/wp-json\/wp\/v2\/tags?post=15393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}