{"id":8521,"date":"2023-11-13T14:58:58","date_gmt":"2023-11-13T14:58:58","guid":{"rendered":"https:\/\/fitolympia.com\/?p=8521"},"modified":"2023-11-13T14:59:06","modified_gmt":"2023-11-13T14:59:06","slug":"how-much-protein-should-i-eat","status":"publish","type":"post","link":"https:\/\/fitolympia.com\/fr\/how-much-protein-should-i-eat\/","title":{"rendered":"QUELLE QUANTIT\u00c9 DE PROT\u00c9INES DOIS-JE MANGER?"},"content":{"rendered":"<\/p>\n<p>Les prot\u00e9ines sont un nutriment que l\u2019on retrouve dans de nombreux types d\u2019aliments. C\u2019est vital pour la vie. Chaque fois que votre corps grandit ou se r\u00e9pare, des prot\u00e9ines sont n\u00e9cessaires. La quantit\u00e9 de prot\u00e9ines dont vous avez besoin d\u00e9pend de plusieurs facteurs , y compris l\u2019\u00e2ge, le sexe, l\u2019\u00e9tat de sant\u00e9 et le niveau d\u2019activit\u00e9.<\/p>\n<p>Le corps a besoin d\u2019un approvisionnement r\u00e9gulier en prot\u00e9ines pour fabriquer et r\u00e9parer les cellules. En plus des muscles, d\u2019autres tissus du corps sont principalement fabriqu\u00e9s \u00e0 partir de prot\u00e9ines, comme les organes, les cheveux et les yeux. Ce nutriment aide \u00e9galement :<\/p>\n<ul>\n<li>Combattre l\u2019infection<\/li>\n<li>Transporter les graisses, les vitamines, les min\u00e9raux et l\u2019oxyg\u00e8ne autour du corps<\/li>\n<li>Construire et contracter les muscles<\/li>\n<li>Maintenir l\u2019\u00e9quilibre des liquides organiques<\/li>\n<li>Sang de caillot<\/li>\n<\/ul>\n<h4>Aliments qui contiennent des prot\u00e9ines<\/h4>\n<p>Les prot\u00e9ines peuvent \u00eatre trouv\u00e9es dans les aliments \u00e0 base d\u2019animaux et de plantes. Certaines sources de prot\u00e9ines sont consid\u00e9r\u00e9es comme de meilleurs choix que d\u2019autres en raison de leur influence sur la sant\u00e9 cardiaque. Les plans alimentaires qui comprennent des produits laitiers faibles en gras, de la volaille sans peau, du poisson, des haricots, des lentilles et des aliments \u00e0 base de soja comme le tofu et le tempeh peuvent aider \u00e0 am\u00e9liorer la pression art\u00e9rielle et le taux de cholest\u00e9rol. Voici quelques options nutritives d\u2019aliments prot\u00e9in\u00e9s :<\/p>\n<ul>\n<li><strong>Viande, volaille et \u0153ufs : coupes\u00a0<\/strong>maigres de b\u0153uf, longe de porc, poulet sans peau et dinde<\/li>\n<li><strong>Poissons et fruits de mer\u00a0<\/strong>: saumon, thon, morue, crevettes<\/li>\n<li><strong>Produits laitiers faibles en gras ou sans gras :<\/strong>\u00a0yogourt, lait, fromage, fromage cottage<\/li>\n<li><strong>L\u00e9gumineuses\u00a0<\/strong>: haricots, pois cass\u00e9s, lentilles, soja<\/li>\n<li><strong>Noix et graines :<\/strong>\u00a0noix, amandes, graines de, graines de citrouille<\/li>\n<\/ul>\n<p>Les aliments riches en prot\u00e9ines peuvent \u00e9galement \u00eatre riches en gras satur\u00e9s. Des apports \u00e9lev\u00e9s en gras satur\u00e9s peuvent augmenter le risque de maladie cardiaque. Ainsi, trop de prot\u00e9ines provenant de ces sources peuvent \u00eatre nocives pour votre c\u0153ur. En r\u00e8gle g\u00e9n\u00e9rale, limitez les aliments prot\u00e9in\u00e9s riches en gras satur\u00e9s, comme :<\/p>\n<ul>\n<li><strong>Viandes et volailles :<\/strong>\u00a0bacon, steak frit au poulet, saucisse chorizo, poulet frit, hot-dogs, viandes de d\u00e9jeuner, viandes d\u2019organes, viandes transform\u00e9es, saucisses et c\u00f4tes lev\u00e9es<\/li>\n<li><strong>Poissons et crustac\u00e9s :<\/strong>\u00a0options pan\u00e9es et frites<\/li>\n<li><strong>Produits laitiers \u00e0 mati\u00e8res grasses enti\u00e8res\u00a0<\/strong>: lait entier et autres produits laitiers \u00e0 mati\u00e8res grasses enti\u00e8res<\/li>\n<\/ul>\n<h4>Obtenir la bonne quantit\u00e9 de prot\u00e9ines<\/h4>\n<p>La plupart des adultes en bonne sant\u00e9 devraient viser l\u2019apport alimentaire recommand\u00e9 en prot\u00e9ines pour leur \u00e2ge et leur sexe. Les personnes qui sont tr\u00e8s actives physiquement, qui sont enceintes ou qui allaitent, ou qui ont certaines conditions m\u00e9dicales peuvent avoir besoin de plus de prot\u00e9ines. Il est \u00e9galement recommand\u00e9 de varier vos choix de prot\u00e9ines.<\/p>\n<p>MyPlate comprend des recommandations g\u00e9n\u00e9rales sur les prot\u00e9ines pour les personnes \u00e2g\u00e9es de 2 ans et plus.<\/p>\n<figure class=\"wp-block-table\">\n<table>\n<tbody>\n<tr>\n<th>\u00c2ge<\/th>\n<th>Sexe<\/th>\n<th>Recommandation quotidienne sur les prot\u00e9ines<\/th>\n<\/tr>\n<tr>\n<td>2-3 ans<\/td>\n<td>Femelle et m\u00e2le<\/td>\n<td>\u00c9quivalents de 2 onces<\/td>\n<\/tr>\n<tr>\n<td>4-8 ans<\/td>\n<td>Femelle et m\u00e2le<\/td>\n<td>\u00c9quivalents de 4 onces<\/td>\n<\/tr>\n<tr>\n<td>9-13 ans<\/td>\n<td>Femelle et m\u00e2le<\/td>\n<td>\u00c9quivalents de 5 onces<\/td>\n<\/tr>\n<tr>\n<td>14-18 ans<\/td>\n<td>Femelle<\/td>\n<td>\u00c9quivalents de 5 onces<\/td>\n<\/tr>\n<tr>\n<td>14-18 ans<\/td>\n<td>M\u00e2le<\/td>\n<td>6 1\/2 once d\u2019\u00e9quivalents<\/td>\n<\/tr>\n<tr>\n<td>19-30 ans<\/td>\n<td>Femelle<\/td>\n<td>5 1\/2 once d\u2019\u00e9quivalents<\/td>\n<\/tr>\n<tr>\n<td>19-30 ans<\/td>\n<td>M\u00e2le<\/td>\n<td>6 1\/2 once d\u2019\u00e9quivalents<\/td>\n<\/tr>\n<tr>\n<td>31-50 ans<\/td>\n<td>Femelle<\/td>\n<td>\u00c9quivalents de 5 onces<\/td>\n<\/tr>\n<tr>\n<td>31-50 ans<\/td>\n<td>M\u00e2le<\/td>\n<td>\u00c9quivalents de 6 onces<\/td>\n<\/tr>\n<tr>\n<td>51 ans et plus<\/td>\n<td>Femelle<\/td>\n<td>\u00c9quivalents de 5 onces<\/td>\n<\/tr>\n<tr>\n<td>51 ans et plus<\/td>\n<td>M\u00e2le<\/td>\n<td>5 1\/2 once d\u2019\u00e9quivalents<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/figure>\n<p>Ces recommandations pour les prot\u00e9ines sont fournies en \u00e9quivalents d\u2019une once. Les \u00e9quivalents d\u2019une once d\u2019aliments prot\u00e9in\u00e9s comprennent :<\/p>\n<ul>\n<li>Une once de viande, de volaille ou de poisson cuits<\/li>\n<li>1\/4 tasse de haricots cuits<\/li>\n<li>1 \u0153uf<\/li>\n<li>1 cuill\u00e8re \u00e0 soupe de beurre d\u2019arachide<\/li>\n<li>1\/2 once de noix ou de graines<\/li>\n<\/ul>\n<p>Mais, la plupart des portions courantes d\u2019aliments prot\u00e9in\u00e9s comprennent plus d\u2019une once de prot\u00e9ines. Par exemple, un morceau de viande de la taille d\u2019un jeu de cartes, d\u2019une bo\u00eete de thon \u00e9goutt\u00e9 et d\u2019une petite moiti\u00e9 de poitrine de poulet \u00e9quivaut \u00e0 environ trois onces de prot\u00e9ines chacune. De plus, les aliments \u00e0 grains entiers et les produits laitiers contiennent des prot\u00e9ines. La plupart des Am\u00e9ricains obtiennent suffisamment de prot\u00e9ines dans l\u2019ensemble, mais le d\u00e9placement de leur consommation pour inclure les fruits de mer deux fois par semaine et les l\u00e9gumineuses plus souvent \u00e0 la place d\u2019autres aliments prot\u00e9in\u00e9s est encourag\u00e9.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>Les prot\u00e9ines sont un nutriment que l\u2019on retrouve dans de nombreux types d\u2019aliments. C\u2019est vital pour la vie. Chaque fois [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8522,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[213,19,165],"tags":[],"class_list":["post-8521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-foods","category-nutrition","category-proteins"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"fr","enabled_languages":["en","es","de","fr","ru","hi","ar","tr","it","pt","na"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"na":{"title":false,"content":false,"excerpt":false}}},"featured_img":"https:\/\/fitolympia.com\/wp-content\/uploads\/2021\/01\/protein-637229718.jpg","categories_details":[{"id":213,"name":"Foods","count":119,"parent":0},{"id":19,"name":"Nutrition","count":205,"parent":0},{"id":165,"name":"Proteins","count":40,"parent":0}],"tags_details":[],"comment_count":0,"author_name":"Staff","author_img":"https:\/\/secure.gravatar.com\/avatar\/0770ff71d5267ad67c1cefbf36008dc2a2753c332616ff451380094010b0d281?s=96&d=mm&r=g","post_views":6070,"_links":{"self":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/8521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/comments?post=8521"}],"version-history":[{"count":9,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/8521\/revisions"}],"predecessor-version":[{"id":17059,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/8521\/revisions\/17059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/media\/8522"}],"wp:attachment":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/media?parent=8521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/categories?post=8521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/tags?post=8521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}