{"id":7370,"date":"2025-05-25T00:00:28","date_gmt":"2025-05-25T00:00:28","guid":{"rendered":"https:\/\/fitolympia.com\/?p=7370"},"modified":"2025-05-26T02:05:30","modified_gmt":"2025-05-26T02:05:30","slug":"protein-shakes-for-beginners-what-should-you-buy-and-when-should-you-drink","status":"publish","type":"post","link":"https:\/\/fitolympia.com\/fr\/protein-shakes-for-beginners-what-should-you-buy-and-when-should-you-drink\/","title":{"rendered":"Shakes prot\u00e9in\u00e9s pour d\u00e9butants : Que devriez-vous acheter et quand devriez-vous boire?"},"content":{"rendered":"<h5 class=\"wp-block-heading\"><strong>\u00ab Les shakes prot\u00e9in\u00e9s font grossir vos muscles. Achetez notre formule secr\u00e8te pour les meilleurs r\u00e9sultats!\u00a0\u00bb &nbsp;<\/strong><\/h5> <p>C\u2019est ce avec quoi beaucoup de blogs et d\u2019entreprises commercialisent leurs produits.<\/p> <p>Vous lisez cet article parce que vous voulez en savoir plus sur les shakes prot\u00e9in\u00e9s:<\/p> <ul class=\"wp-block-list\"><li>Will it help me build muscle? I\u2019m a skinny dude.<\/li><li>Will it help me lose fat? I\u2019m an overweight male\/female.<\/li><li>Are they a waste of money? Are certain brands better than others?<\/li><\/ul> <p>Ind\u00e9pendamment de ce que vous avez entendu sur les shakes prot\u00e9in\u00e9s, je voulais remettre les pendules \u00e0 l\u2019heure et vous aider \u00e0 commencer \u00e0 les boire, y compris ce qu\u2019il faut acheter et quand les boire!<\/p> <p>Je les bois de temps en temps depuis 15 ans et j\u2019ai essay\u00e9 \u00e0 peu pr\u00e8s toutes les saveurs et tous les types sous le soleil.<\/p> <p><strong>Les shakes prot\u00e9in\u00e9s sont une petite pi\u00e8ce du puzzle.<\/strong>&nbsp;Vous devez AUSSI vous entra\u00eener correctement et bien manger pour obtenir les r\u00e9sultats que vous recherchez. Apr\u00e8s tout, si vous mangez comme des ordures et que vous vous entra\u00eenez mal, tous les shakes prot\u00e9in\u00e9s du monde ne vous aideront pas \u00e0 devenir plus fort et plus gros!<\/p> <p>Vous devez avoir les bons syst\u00e8mes, la bonne strat\u00e9gie nutritionnelle et le bon entra\u00eenement en place, et ALORS un shake prot\u00e9in\u00e9 pourrait vous aider \u00e0 atteindre vos objectifs un peu plus rapidement.<\/p> <p>Nous savons que ce genre de choses est compliqu\u00e9, et nous savons que c\u2019est nul quand vous passez 6 \u00e0 12 mois \u00e0 boire des shakes prot\u00e9in\u00e9s et \u00e0 ne PAS obtenir de r\u00e9sultats (ce que j\u2019ai fait quand j\u2019ai commenc\u00e9 \u2013 sauf que je l\u2019ai fait pendant 6 ans!). Vous n\u2019avez probablement pas 12 mois \u00e0 perdre, et vous voulez prendre ce genre de choses au s\u00e9rieux!<\/p> <p>Pour aider les personnes occup\u00e9es comme vous \u00e0 ne pas perdre leur temps au gymnase et les aider \u00e0 obtenir des r\u00e9sultats, nous avons cr\u00e9\u00e9 notre programme de coaching en ligne 1 contre 1. Des plans d\u2019entra\u00eenement artisanaux, des strat\u00e9gies nutritionnelles pour votre style de vie, des conseils professionnels et une responsabilit\u00e9 d\u2019expert vous aident \u00e0 r\u00e9duire l\u2019encombrement et \u00e0 commencer \u00e0 obtenir des r\u00e9sultats d\u00e8s aujourd\u2019hui. Vous pouvez planifier un appel avec notre \u00e9quipe en cliquant sur l\u2019image ci-dessous pour voir si nous sommes un bon ajustement les uns pour les autres!<\/p> <div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/giantfitnessclubs.com\/wp-content\/uploads\/2019\/03\/GettyImages-464416582-1024x576.jpg\" alt=\"\" class=\"wp-image-6342\"\/><\/figure><\/div> <h1 class=\"wp-block-heading\"><strong>Ce que vous devez savoir sur les suppl\u00e9ments de prot\u00e9ines<\/strong><\/h1> <p><strong>Un suppl\u00e9ment de prot\u00e9ines devrait&nbsp;<em>supplement<\/em>&nbsp;une alimentation saine.<\/strong><\/p> <p>Cela signifie que dans la mesure du possible, vous devriez viser \u00e0 obtenir votre apport quotidien en prot\u00e9ines \u00e0 partir de sources alimentaires r\u00e9elles:<\/p> <p>Poulet, steak, hamburgers, amandes, arachides, \u0153ufs, poisson, lait, etc.<\/p> <p>Maintenant, en fonction de la quantit\u00e9 de nourriture que vous cherchez \u00e0 manger chaque jour (ou si vous \u00eates un nerd maigre qui a besoin de grossir), manger toute cette nourriture peut co\u00fbter cher.<\/p> <p>En plus de cela, pr\u00e9parer et manger et nettoyer constamment une tonne de repas peut \u00eatre une douleur dans le cul, c\u2019est l\u00e0 que les shakes prot\u00e9in\u00e9s entrent en jeu! Je ne suis pas di\u00e9t\u00e9tiste ou bodybuilder, donc les conseils ci-dessous proviennent de l\u2019exp\u00e9rience personnelle et des suggestions de personnes respect\u00e9es en qui j\u2019ai confiance.<\/p> <p><strong>Choses \u00e0 garder \u00e0 l\u2019esprit lors de l\u2019achat, ce qui est l\u2019humble opinion de ce nerd<\/strong>:<\/p> <ul class=\"wp-block-list\"><li><strong>To start out, buy 100%&nbsp;<\/strong><strong>whey protein<\/strong>. There are other kinds of protein powders that I\u2019ll go into on another post \u2013 egg protein, hemp protein, etc. For now, keep it simple and basic and look for something that says \u201c100% Whey on it\u201d<\/li><li><strong>When buying protein powders, you want to try and buy a product with minimal other \u2018stuff.\u2019&nbsp;<\/strong>Low carbs, low sugar, low sodium, low calories, low fat, etc. If you go into a vitamin or nutrition store, always check the label before buying.<\/li><li><strong>Pick a flavor that you like!&nbsp;<\/strong>Protein powders generally come in a few flavors: vanilla, chocolate, strawberry, etc.<\/li><li><strong>If you\u2019re a picky eater, buy a few single servings before you invest in a 3 month supply of protein powder.<\/strong><\/li><li><strong>Like the flavor? Buy in bulk when possible<\/strong>. Many places online will offer free shipping on orders over $x amount. If you\u2019re serious about fitness and think you\u2019ll be drinking shakes for the foreseeable future, buy a few tubs at once and save on shipping.<\/li><\/ul> <div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/giantfitnessclubs.com\/wp-content\/uploads\/2019\/03\/truth-about-protein.jpg\" alt=\"\" class=\"wp-image-6347\"\/><\/figure><\/div> <p>Le lactos\u00e9rum nourri \u00e0 l\u2019herbe est beaucoup plus cher que l\u2019option Optimum Nutrition, mais j\u2019ai trouv\u00e9 les deux d\u00e9licieux, plein de prot\u00e9ines et utile pour atteindre mon nombre de prot\u00e9ines chaque jour. Comme je l\u2019ai dit ci-dessus, votre suppl\u00e9ment de prot\u00e9ines devrait faire partie d\u2019une alimentation saine.<\/p> <p>Le simple fait de boire un shake prot\u00e9in\u00e9 tout en mangeant comme de la merde ne vous donnera pas les r\u00e9sultats que vous recherchez. Vous devez bien manger, suivre une routine de musculation et vous concentrer sur les progr\u00e8s!<\/p> <p>Si vous vous sentez perdu avec vos s\u00e9ances d\u2019entra\u00eenement ou si vous ne savez pas quoi faire avec votre alimentation, t\u00e9l\u00e9chargez nos guides gratuits lorsque vous vous inscrivez dans la case ci-dessous et vous pouvez arr\u00eater de vous inqui\u00e9ter et commencer \u00e0 faire des progr\u00e8s AUJOURD\u2019HUI:<\/p> <div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/giantfitnessclubs.com\/wp-content\/uploads\/2019\/03\/protein-shake-powder-on-a-spoon-and-made-in-a-glass-1024x683.jpg\" alt=\"\" class=\"wp-image-6343\"\/><\/figure><\/div> <h1 class=\"wp-block-heading\"><strong>Quelle quantit\u00e9 de prot\u00e9ines dois-je consommer chaque jour?<\/strong><\/h1> <p><strong>Malgr\u00e9 ce que les publicit\u00e9s pour les suppl\u00e9ments de prot\u00e9ines vous diront, vous n\u2019avez pas besoin de manger des centaines de grammes de prot\u00e9ines chaque jour.<\/strong><\/p> <p>Ils aiment vous dire cela afin que vous utilisiez leur suppl\u00e9ment plus rapidement et que vous ayez besoin d\u2019en acheter plus!<\/p> <p>Bien qu\u2019il n\u2019y ait pas de science exacte \u00e0 cela, et que tout le monde soit un flocon de neige unique, nous aimons garder les choses simples ici \u00e0 Nerd Fitness.<\/p> <p>Les all\u00e9gations relatives \u00e0 la quantit\u00e9 de prot\u00e9ines n\u00e9cessaire varient \u00e9norm\u00e9ment d\u2019une source \u00e0 l\u2019autre (et d\u2019un athl\u00e8te \u00e0 l\u2019autre).<\/p> <p><strong>Personnellement, j\u2019ai trouv\u00e9 que 1 gramme de prot\u00e9ines par livre de&nbsp;<em>lean body weight<\/em>&nbsp;(2 grammes par poids corporel maigre de kg) fonctionne pour la plupart des gens.<\/strong>&nbsp;Si vous n\u2019\u00eates pas int\u00e9ress\u00e9 \u00e0 d\u00e9terminer votre&nbsp;pourcentage de graisse corporelle&nbsp;pour d\u00e9terminer votre poids corporel maigre, ce n\u2019est pas grave non plus.<\/p> <p>Restez tr\u00e8s simple:<\/p> <p>Manger 0,8 gramme de prot\u00e9ines par livre de poids corporel total, ou 1,6 gramme de prot\u00e9ines par kg. Fait.<\/p> <p>Notez que vos prot\u00e9ines ne sont qu\u2019une partie d\u2019une alimentation saine! Vous devriez remplir votre estomac avec des aliments nutritifs comme des l\u00e9gumes, de haute qualit\u00e9 et des graisses saines. En savoir plus sur&nbsp;alimentation saine ici.<\/p> <div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/giantfitnessclubs.com\/wp-content\/uploads\/2019\/03\/maxresdefault-10-1024x576.jpg\" alt=\"\" class=\"wp-image-6344\"\/><\/figure><\/div> <h1 class=\"wp-block-heading\"><strong>Avec quoi le m\u00e9langer?<\/strong><\/h1> <p><strong>Exp\u00e9rience personnelle: le c\u00f4t\u00e9 de l\u2019\u00e9tiquette vous dit de m\u00e9langer une cuill\u00e8re dans 8 oz d\u2019eau et elle \u00ab\u00a0se m\u00e9lange bien et a bon go\u00fbt!\u00a0\u00bb<\/strong><\/p> <p>Je ne connais pas la version au chocolat, mais la poudre de vanille \/ fraise m\u00e9lang\u00e9e \u00e0 de l\u2019eau n\u2019est pas g\u00e9niale, bien qu\u2019elle soit g\u00e9rable. Je trouve que c\u2019est mieux lorsqu\u2019il est m\u00e9lang\u00e9 avec un m\u00e9langeur qu\u2019une bouteille de shaker, mais faites ce que vous pouvez.<\/p> <p><em>Instead, I mix one scoop in with 8+ oz of&nbsp;whole milk&nbsp;or almond milk.<\/em><\/p> <p><strong>Vous voulez de la vari\u00e9t\u00e9?&nbsp;<\/strong>Ajoutez des bananes, des fraises, des bleuets, du beurre d\u2019arachide, du lait d\u2019amande, etc.&amp;nbsp; Essayez diff\u00e9rentes combinaisons et trouvez quelque chose que vous aimez vraiment.&amp;nbsp; Si vous pouvez \u00e9touffer l\u2019eau pure et la poudre de prot\u00e9ines, vous \u00eates un homme plus fort que moi.<\/p> <p><strong>Dans quoi le m\u00e9langer?&nbsp;<\/strong>Pendant plus d\u2019une d\u00e9cennie, j\u2019ai simplement utilis\u00e9 un m\u00e9langeur bon march\u00e9 comme celui-ci sur Amazon!<\/p> <p>Selon votre budget, vous pouvez \u00e9galement vous rendre chez votre Walmart local, Target, Kroger, Publix, Sam\u2019s Club, Stop &amp; Shop, etc. et acheter un m\u00e9langeur pour 20 dollars.<\/p> <p><strong>Les m\u00e9langeurs Vitamix ne sont pas bon march\u00e9, mais ils<\/strong>&nbsp;valent certainement l\u2019argent. Ils sont chers, bien s\u00fbr&#8230; mais vous en avez pour votre argent. J\u2019ai probablement br\u00fbl\u00e9 les moteurs de plus de 10 m\u00e9langeurs bon march\u00e9, et depuis que je suis pass\u00e9 \u00e0 un Vitamix, il \u00e9crase mes ingr\u00e9dients de shake \u00e9lectrique deux fois par jour en quelques secondes.<\/p> <p><em>If you have the money, it\u2019s worth the investment.&nbsp;<\/em><\/p> <p><strong>Votre autre option est d\u2019acheter un shaker pas cher<\/strong>, qui contient un \u00e9l\u00e9ment de type rayon pour briser la poudre lorsque vous la m\u00e9langez avec du lait, de l\u2019eau, du JO, peu importe.&nbsp; Personnellement, j\u2019ai constat\u00e9 que ces choses ne fonctionnent pas aussi bien qu\u2019un m\u00e9langeur. Vous pouvez secouer un m\u00e9langeur pendant 3 minutes et il ne sera toujours pas aussi bon d\u2019un m\u00e9lange que 15 secondes sur un m\u00e9langeur.<\/p> <p>Remarque: si vous utilisez une bouteille de shaker, versez d\u2019abord l\u2019eau, PUIS ajoutez le shake prot\u00e9in\u00e9!<\/p> <figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/giantfitnessclubs.com\/wp-content\/uploads\/2019\/03\/Weight-Loss-Protein-Smoothie-1024x681.jpg\" alt=\"\" class=\"wp-image-6345\"\/><\/figure> <h1 class=\"wp-block-heading\"><strong>Quand les boire?<\/strong><\/h1> <p>\u00c0 mon avis, d\u2019apr\u00e8s mon exp\u00e9rience et mes recherches, je crois que le moment le plus important pour boire un shake est juste apr\u00e8s votre entra\u00eenement de force chaque fois que possible.<\/p> <p>C\u2019est \u00e0 ce moment-l\u00e0 que vos muscles ont \u00e9t\u00e9 d\u00e9compos\u00e9s par l\u2019exercice et ont d\u00e9sesp\u00e9r\u00e9ment besoin de prot\u00e9ines pour se reconstruire. Si vous pouvez manger un repas nutritif apr\u00e8s votre entra\u00eenement, c\u2019est encore mieux. Si ce n\u2019est pas le cas, ou si votre estomac a des maux d\u2019estomac lorsque vous mangez apr\u00e8s une s\u00e9ance d\u2019entra\u00eenement, envisagez un suppl\u00e9ment de prot\u00e9ines ou un smoothie prot\u00e9in\u00e9 fait maison pour obtenir \u00e0 votre corps les nutriments dont il a besoin!<\/p> <p>Si vous \u00eates un gars maigre qui essaie de gagner du muscle, vous allez manger beaucoup de calories et vouloir cibler plus pr\u00e8s de 1 gramme de prot\u00e9ines par livre de poids corporel total chaque jour. Ajustez cela en fonction de vos progr\u00e8s, de votre m\u00e9tabolisme, etc.<\/p> <p>Une note rapide ici: tous les shakes prot\u00e9in\u00e9s dans le monde ne vous aideront pas \u00e0 devenir plus gros et plus fort si vous ne mangez pas assez de calories totales tous les jours &#8211; j\u2019ai pass\u00e9 5 ans \u00e0 faire de la musculation et \u00e0 boire des shakes prot\u00e9in\u00e9s et je n\u2019ai pas mis une livre de muscle. C\u2019est parce que je n\u2019avais pas un bon plan d\u2019entra\u00eenement \u00e0 suivre et que je ne mangeais pas assez de calories tous les jours.<\/p> <p>Si vous ne grossissez pas, vous ne mangez pas assez.<\/p> <p><strong>Vous avez du mal \u00e0 manger suffisamment de calories tous les jours?<\/strong>&nbsp;Pensez \u00e0 faire trembler ma puissance que je consomme apr\u00e8s l\u2019entra\u00eenement (remarque, vous aurez besoin d\u2019un m\u00e9langeur puissant pour faire cela, c\u2019est BEAUCOUP pour un m\u00e9langeur bon march\u00e9 \u00e0 traiter et br\u00fblera probablement le moteur):<\/p> <p><strong>RECETTE POWER SHAKE<\/strong><\/p> <ul class=\"wp-block-list\"><li>2 cups of whole milk<\/li><li>1.5 cups of quaker oats<\/li><li>1.5 scoops of whey protein<\/li><li>1 cup of frozen spinach<\/li><li>1 cup of frozen berries<\/li><\/ul> <p>Ajustez les ingr\u00e9dients en fonction de vos objectifs, du nombre de calories que vous devez consommer chaque jour et faites-le fonctionner pour vous!<\/p> <p>Rappelez-vous, rien de ce qui pr\u00e9c\u00e8de n\u2019aura d\u2019importance si vous ne suivez pas \u00e9galement une excellente routine de musculation!<\/p> <p>Si vous ne faites que commencer et que vous avez besoin d\u2019un plan d\u2019entra\u00eenement \u00e0 suivre, t\u00e9l\u00e9chargez notre guide gratuit,&nbsp;<em>Strength Training 101: Everything You Need to Know<\/em>, et notre&nbsp;<em>Skinny Nerd Bulk Up Cheat Sheet<\/em>&nbsp;lorsque vous vous inscrivez dans la case ci-dessous :<\/p> <div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/giantfitnessclubs.com\/wp-content\/uploads\/2019\/03\/Vegan-protein-shake-683x1024.jpg\" alt=\"\" class=\"wp-image-6346\"\/><\/figure><\/div> <h1 class=\"wp-block-heading\"><strong>R\u00e9capitulatif des prot\u00e9ines<\/strong><\/h1> <p><strong>Les suppl\u00e9ments de prot\u00e9ines devraient COMPL\u00c9TER une alimentation saine, pas la remplacer.<\/strong><\/p> <p>Envisagez de m\u00e9langer un shake prot\u00e9in\u00e9 apr\u00e8s votre entra\u00eenement, c\u2019est s\u00fbr, puis chaque fois que vous \u00eates entre les repas et que vous avez besoin de prot\u00e9ines.<\/p> <p>Pensez \u00e0 un shake comme un moyen d\u2019obtenir de bonnes prot\u00e9ines lorsque vous ne pouvez pas vous permettre \/ n\u2019avez pas le temps de faire un bon repas.<\/p> <p>Un m\u00e9langeur bon march\u00e9 suffira si vous n\u2019avez pas d\u2019autres options, mais si vous avez plus de budget, je vous recommande d\u2019obtenir un Vitamix pour les 30 prochaines ann\u00e9es.<\/p> <p>J\u2019esp\u00e8re que cela devrait vous aider \u00e0 d\u00e9marrer! N\u2019h\u00e9sitez pas \u00e0 essayer diff\u00e9rentes saveurs et combinaisons d\u2019ingr\u00e9dients dans vos smoothies pour en faire quelque chose que vous attendez avec impatience!<\/p> <p><a href=\"https:\/\/giantfitnessclubs.com\/protein-shakes-for-beginners-what-should-you-buy-and-when-should-you-drink\/#\"><\/a><\/p> ","protected":false},"excerpt":{"rendered":"<p>\u00ab Les shakes prot\u00e9in\u00e9s font grossir vos muscles. Achetez notre formule secr\u00e8te pour les meilleurs r\u00e9sultats!\u00a0\u00bb &nbsp; C\u2019est ce avec [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[165],"tags":[],"class_list":["post-7370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proteins"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"fr","enabled_languages":["en","es","de","fr","ru","hi","ar","tr","it","pt","na"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"na":{"title":false,"content":false,"excerpt":false}}},"featured_img":"https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/11\/Big__fgrt.jpg","categories_details":[{"id":165,"name":"Proteins","count":40,"parent":0}],"tags_details":[],"comment_count":0,"author_name":"Staff","author_img":"https:\/\/secure.gravatar.com\/avatar\/0770ff71d5267ad67c1cefbf36008dc2a2753c332616ff451380094010b0d281?s=96&d=mm&r=g","post_views":19594,"_links":{"self":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/7370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/comments?post=7370"}],"version-history":[{"count":8,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/7370\/revisions"}],"predecessor-version":[{"id":17750,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/7370\/revisions\/17750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/media\/7371"}],"wp:attachment":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/media?parent=7370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/categories?post=7370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/tags?post=7370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}