{"id":6861,"date":"2024-11-10T00:00:32","date_gmt":"2024-11-10T00:00:32","guid":{"rendered":"https:\/\/fitolympia.com\/?p=6861"},"modified":"2024-11-10T17:52:53","modified_gmt":"2024-11-10T17:52:53","slug":"9-vitamin-d-benefits-you-should-know-and-how-to-get-more-in-your-diet","status":"publish","type":"post","link":"https:\/\/fitolympia.com\/fr\/9-vitamin-d-benefits-you-should-know-and-how-to-get-more-in-your-diet\/","title":{"rendered":"9 avantages de la vitamine D que vous devriez savoir"},"content":{"rendered":"<p>Vous savez d\u00e9j\u00e0 que la vitamine D est importante pour la sant\u00e9 des os, mais ses avantages ne s\u2019arr\u00eatent pas l\u00e0.<\/p> <p>Vitamin D\u2014nicknamed the &#8220;sunshine vitamin&#8221; due to its ability to be absorbed by the body through sunlight\u2014is a major player in keeping the human body healthy. Its main job, according to the&nbsp;<a href=\"https:\/\/ods.od.nih.gov\/factsheets\/VitaminD-HealthProfessional\/\" target=\"_blank\" rel=\"noreferrer noopener\">National Institutes of Health&#8217;s Office of Dietary Supplements<\/a>, est de promouvoir&nbsp;<a href=\"https:\/\/www.health.com\/nutrition\/14-non-dairy-foods-that-are-high-in-calcium\">calcium<\/a>&nbsp;absorption, ce qui le rend n\u00e9cessaire \u00e0 la croissance osseuse et au remodelage osseux (lorsque le tissu osseux mature est enlev\u00e9 et que de nouveaux tissus osseux sont form\u00e9s). Pour cette raison, un manque de vitamine D peut conduire \u00e0 des os minces, cassants ou difformes. Mais la vitamine D offre \u00e9galement une gamme d\u2019autres avantages, allant de positifs pour la sant\u00e9 physique et mentale. Voici neuf avantages de la vitamine D que vous devez conna\u00eetre, y compris les moyens de&nbsp;<a href=\"https:\/\/www.health.com\/condition\/osteoporosis\/12-ways-to-get-your-daily-vitamin-d\">get more of the vitamin<\/a>&nbsp;dans votre alimentation quotidienne.<\/p> <h2 class=\"wp-block-heading\"><strong>La vitamine D renforce vos os&nbsp;<\/strong><\/h2> <p>La vitamine D est c\u00e9l\u00e8bre pour ses pouvoirs de construction osseuse et de renforcement. \u00ab\u00a0La vitamine D favorise l\u2019absorption du calcium dans votre intestin, ce qui permet finalement une min\u00e9ralisation normale de vos os\u00a0\u00bb.&nbsp;<a href=\"http:\/\/jackienewgent.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jackie Newgent, RDN<\/a>, nutritionniste culinaire et auteur de&nbsp;<em>The Clean &amp; Simple Diabetes Cookbook<\/em>, raconte&nbsp;<em>Health<\/em>. Fondamentalement, le calcium qui profite \u00e0 vos os ne serait pas en mesure de faire son travail sans la vitamine D. \u00ab\u00a0Vous avez besoin de vitamine D pour la croissance osseuse &#8211; et pour emp\u00eacher les os de devenir fragiles.\u00a0\u00bb Lorsqu\u2019il est associ\u00e9 au calcium, il peut aider \u00e0 pr\u00e9venir l\u2019ost\u00e9oporose, une maladie qui signifie que la densit\u00e9 et la qualit\u00e9 des os sont r\u00e9duites, ajoute-t-elle.<\/p> <h2 class=\"wp-block-heading\"><strong>La vitamine D peut aider \u00e0 renforcer les muscles&nbsp;<\/strong><\/h2> <p>En plus de ses capacit\u00e9s de construction osseuse, la vitamine D est \u00e9galement influente dans le renforcement des muscles. \u00ab\u00a0Le manque de vitamine D dans le corps peut augmenter le risque d\u2019avoir des muscles faibles, ce qui augmente le risque de chutes\u00a0\u00bb, explique Lana Nasrallah, MPH, RD, di\u00e9t\u00e9ticienne clinique \u00e0 UNC Health.<em>Health<\/em>. Ceci est particuli\u00e8rement important pour les personnes \u00e2g\u00e9es. \u00ab\u00a0La vitamine D peut aider \u00e0 augmenter la force musculaire, pr\u00e9venant ainsi les chutes, ce qui est un probl\u00e8me courant qui entra\u00eene une invalidit\u00e9 importante et la mort chez les personnes \u00e2g\u00e9es.\u00a0\u00bb<\/p> <h2 class=\"wp-block-heading\"><strong>La vitamine D peut soutenir le syst\u00e8me immunitaire et combattre l\u2019inflammation&nbsp;<\/strong><\/h2> <p>Le Dr Nasrallah ajoute que la vitamine D peut \u00e9galement aider \u00e0 renforcer l\u2019immunit\u00e9. \u00ab\u00a0Il peut soutenir le syst\u00e8me immunitaire en combattant les bact\u00e9ries et les virus nocifs\u00a0\u00bb, dit-elle. En fait, ce r\u00f4le dans la pr\u00e9vention \u00e9ventuelle des infections est devenu une pr\u00e9occupation majeure pendant la pand\u00e9mie de COVID-19, car les chercheurs s\u2019int\u00e9ressent \u00e0 son r\u00f4le potentiel dans les r\u00e9sultats de l\u2019infection. \u00ab\u00a0Son r\u00f4le dans les infections virales telles que la grippe et le coronavirus s\u2019int\u00e9resse particuli\u00e8rement aux infections virales,&#8221;&nbsp;<a href=\"https:\/\/www.yalemedicine.org\/doctors\/barry_boyd\/\" target=\"_blank\" rel=\"noreferrer noopener\">Barry Boyd, MD, RDN<\/a>, un h\u00e9matologue, oncologue et nutritionniste de Yale Medicine, raconte&nbsp;<em>Health<\/em>. Il pointe du point a&nbsp;<a href=\"https:\/\/www.bmj.com\/content\/356\/bmj.i6583?ijkey=6723348431cc5e0729c739a9454ef98f47c2a90e&amp;keytype2=tf_ipsecsha\" target=\"_blank\" rel=\"noreferrer noopener\">2017&nbsp;<em>BMJ<\/em>&nbsp;analysis<\/a>&nbsp;of 25 randomized control trials comparing vitamin D supplements to placebos, which found that vitamin D reduced the risk of acute respiratory infection with either daily or weekly vitamin D supplementation, particularly in individuals who were deficient in it. \u201cStudies indicate that high latitudes and winter season are risk factors for both low vitamin D, increased influenza, and other respiratory illness and adverse outcomes,\u201d he says. \u201cWe now are seeing a similar pattern with higher mortality rates in COVID-19 infections,&#8221; though more research still needs to be done to determine whether the link is causal or merely a correlation.&nbsp;<\/p> <h2 class=\"wp-block-heading\"><strong>La vitamine D peut aider \u00e0 renforcer la sant\u00e9 buccodentaire<\/strong><\/h2> <p>Parce que la vitamine D aide notre corps \u00e0 absorber le calcium, elle joue un r\u00f4le crucial dans le soutien de la sant\u00e9 bucco-dentaire, r\u00e9duisant le risque de carie dentaire et de maladie des gencives. Une revue de 2011 dans&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/21748977\/\" target=\"_blank\"><em>The Journal of the Tennessee Dental Association<\/em><\/a>&nbsp;notes that while the research is scant, there&#8217;s an &#8220;emerging hypothesis&#8221; that the vitamin is beneficial for oral health, due to its effect on bone metabolism and &#8220;its ability to function as an anti-inflammatory agent and stimulate the production of anti-microbial peptides.&#8221;<\/p> <h2 class=\"wp-block-heading\"><strong>La vitamine D peut aider \u00e0 pr\u00e9venir le diab\u00e8te de type 1 et de type 2&nbsp;<\/strong><\/h2> <p>Bien que les \u00e9tudes ne soient pas concluantes, la vitamine D peut \u00eatre utile pour pr\u00e9venir le diab\u00e8te de type 1 et de type 2, dit Newgent. Une de ces \u00e9tudes, publi\u00e9e en 2006 dans la revue&nbsp;<em><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/16505521\/\" target=\"_blank\" rel=\"noreferrer noopener\">Diabetes Care<\/a><\/em>, a constat\u00e9 que, bien que la vitamine D \u00e0 elle seule ne r\u00e9duise pas efficacement le risque d\u2019une surabondance de sucre dans le sang, un apport quotidien combin\u00e9 de 1 200 mg de calcium &gt; et &gt; de 800 UI de vitamine D pourrait r\u00e9duire efficacement le risque de diab\u00e8te de type 2.<\/p> <h2 class=\"wp-block-heading\"><strong>La vitamine D peut aider \u00e0 traiter l\u2019hypertension<\/strong><\/h2> <p>Selon une revue de 2019 publi\u00e9e dans la revue&nbsp;<em><a rel=\"noreferrer noopener\" href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/31389312\/\" target=\"_blank\">Current Protein &amp; Peptide Science<\/a><\/em>&nbsp;suggests that vitamin D may play a role in treatment of high blood pressure\u2014one of the markers of cardiovascular disease\u2014says Newgent. According to authors of the review, \u201ceven short-term vitamin D deficiency may directly raise BP [blood pressure] and promote target organ damage.\u201d The researchers went on to add that, &#8220;due to the high correlation between vitamin D and hypertension, vitamin D supplementation therapy may be a new insight in the treatment of hypertension.&#8221;<\/p> <h2 class=\"wp-block-heading\"><strong>La vitamine D peut vous aider \u00e0 perdre du poids&nbsp;<\/strong><\/h2> <p>Le Dr Boyd souligne que l\u2019ob\u00e9sit\u00e9 est un facteur de risque connu pour les faibles niveaux de vitamine D, ce qui signifie que plus de vitamine D peut aider \u00e0 perdre du poids. Une \u00e9tude de 2009 dans le&nbsp;<a href=\"http:\/\/journals.cambridge.org\/action\/displayAbstract?fromPage=online&amp;aid=4454676&amp;fileId=S0007114508030808\" target=\"_blank\" rel=\"noreferrer noopener\"><em>British Journal of Nutrition<\/em><\/a>&nbsp;a constat\u00e9 que, chez les femmes en surpoids ou ob\u00e8ses ayant un faible taux de calcium, celles qui prenaient une dose quotidienne de calcium associ\u00e9e \u00e0 de la vitamine D perdaient plus de poids que celles qui prenaient un suppl\u00e9ment placebo, en raison d\u2019un \u00ab\u00a0effet coupe-faim\u00a0\u00bb de la combinaison.<\/p> <h2 class=\"wp-block-heading\"><strong>La vitamine D peut aider \u00e0 combattre la d\u00e9pression&nbsp;<\/strong><\/h2> <p>Le soleil peut \u00e9gayer votre humeur, tout comme la vitamine D. Selon un article de synth\u00e8se de 2017 dans la revue&nbsp;<em><a rel=\"noreferrer noopener\" href=\"http:\/\/www.jneuropsychiatry.org\/peer-review\/depression-and-vitamin-d-deficiency-causality-assessment-and-clinical-practice-implications-12051.html\" target=\"_blank\">Neuropsychology<\/a><\/em>, researchers found &#8220;a significant relationship between depression and vitamin D deficiency.\u201d While they acknowledged that more research is needed to define the exact workings of it\u2014such as, if low vitamin D levels are a cause or effect of depression\u2014the authors recommend \u201cscreening for and treating vitamin D deficiency in subjects with depression\u201d noting that it is an \u201ceasy, cost-effective and may improve depression outcome.\u201d<\/p> <h2 class=\"wp-block-heading\"><strong>La vitamine D peut aider \u00e0 r\u00e9duire le risque de certains cancers.<\/strong><\/h2> <p>Le Dr Boyd souligne diverses \u00e9tudes, dont la plupart sont r\u00e9f\u00e9renc\u00e9es sur le&nbsp;<a href=\"https:\/\/www.cancer.gov\/about-cancer\/causes-prevention\/risk\/diet\/vitamin-d-fact-sheet\" target=\"_blank\" rel=\"noreferrer noopener\">National Cancer Institute&#8217;s (NCI) website<\/a>&#8230; qui fournissent des preuves que la vitamine D peut avoir des pouvoirs de lutte contre le cancer. \u00ab\u00a0Les preuves augmentent que la suppl\u00e9mentation en vitamine D peut am\u00e9liorer les r\u00e9sultats du cancer\u00a0\u00bb, explique-t-il. Les cancers pour lesquels la plupart des donn\u00e9es humaines sont disponibles sont le cancer colorectal, le cancer du sein, le cancer de la prostate et le cancer du pancr\u00e9as.<\/p> <p>Le NCI appelle sp\u00e9cifiquement quelques raisons pour lesquelles les chercheurs s\u2019int\u00e9ressent \u00e0 un lien entre la vitamine D et un risque r\u00e9duit de cancer. L\u2019organisation souligne que certaines recherches montrent que l\u2019incidence et les taux de mortalit\u00e9 de certains cancers \u00e9taient plus faibles chez les personnes vivant sous les latitudes m\u00e9ridionales, o\u00f9 les niveaux d\u2019exposition au soleil sont relativement \u00e9lev\u00e9s, que chez celles vivant aux latitudes septentrionales, bien que des recherches suppl\u00e9mentaires doivent \u00eatre effectu\u00e9es pour trouver un lien causal ou corr\u00e9lationnel sp\u00e9cifique entre une plus grande exposition au soleil et un risque plus faible de cancer. D\u2019autres preuves exp\u00e9rimentales, selon le NCI, montrent que les cellules canc\u00e9reuses et les tumeurs chez la souris, la vitamine D ont plusieurs activit\u00e9s qui pourraient ralentir ou emp\u00eacher le d\u00e9veloppement des cellules canc\u00e9reuses et des tumeurs chez la souris, notamment la promotion de la diff\u00e9renciation cellulaire, la diminution de la croissance des cellules canc\u00e9reuses, la stimulation de la mort cellulaire (apoptose) et la r\u00e9duction de la formation de vaisseaux sanguins tumoraux (angiogen\u00e8se).<\/p> <h2 class=\"wp-block-heading\">Comment obtenir plus de vitamine D<\/h2> <p>Bien qu\u2019ils soient facilement disponibles par la lumi\u00e8re du soleil, certains aliments et la suppl\u00e9mentation, de nombreux Am\u00e9ricains obtiennent encore des quantit\u00e9s insuffisantes de vitamine D \u2013 selon les informations les plus r\u00e9centes des Centers for Disease Control and Prevention, les deux tiers de la population avaient suffisamment de vitamine D, d\u00e9finie par l\u2019Institute of Medicine comme une valeur s\u00e9rique de 25-hydroxyvitamine D (25OHD) de 50-125 nmol \/ L. Parce que vous ne pouvez pas n\u00e9cessairement savoir si vous avez une carence en vitamine D par vous-m\u00eame, la meilleure chose \u00e0 faire est de consulter un expert m\u00e9dial, dit Cynthia Sass, RD, MPH, r\u00e9dactrice en chef de la nutrition pour&nbsp;<em>Health<\/em>. &#8220;Ideally the best approach is to have your blood vitamin D level tested to find out if your blood vitamin D level is within the adequate range,\u201d she explains. \u201cThis determines if a supplement is needed in order to achieve adequate blood vitamin D status, and if so, the proper dosage of supplemental vitamin D.\u201d&nbsp;<\/p> <figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/imagesvc.meredithcorp.io\/v3\/mm\/image?url=https%3A%2F%2Fstatic.onecms.io%2Fwp-content%2Fuploads%2Fsites%2F12%2F2020%2F06%2F25%2Fvitamin-d-AdobeStock_270150827.jpg&amp;q=85\" alt=\"vitamin-D-benefits , Foods rich in natural vitamin D. Top view, flat lay\" title=\"vitamin-D-benefits\"\/><\/figure> <p>If you find out you are deficient or lacking in vitamin D intake, there are a few key ways you can up your daily dosage\u2014staring with getting around 20 minutes of sunlight several times a week, according to Newgent. &#8220;The major cause of vitamin D deficiency is inadequate exposure to sunlight, an increasing feature in modern life,&#8221; says Dr. Boyd. But remember: You still need to wear sunscreen whenever you step outside\u2014even to get vitamin D.<\/p> <p>Outre le soleil, vous pouvez \u00e9galement obtenir de la vitamine D suppl\u00e9mentaire gr\u00e2ce \u00e0 quelques aliments (bien que tr\u00e8s peu nombreux), comme les poissons gras (y compris le saumon, le thon, le maquereau et les sardines) et les champignons (dont certains sont expos\u00e9s \u00e0 la lumi\u00e8re ultraviolette (UV) pour augmenter les niveaux de vitamine D), disent les Drs Nasrallah et Newgent. Les aliments comme le lait, le jus d\u2019orange, le yogourt et les c\u00e9r\u00e9ales pour petit-d\u00e9jeuner peuvent \u00e9galement \u00eatre enrichis en vitamine D. Et bien s\u00fbr, vous pouvez toujours suivre la voie du suppl\u00e9ment, sous forme de vitamine D3, si votre m\u00e9decin pense que c\u2019est n\u00e9cessaire. Selon le Dr Boyd, de nombreux m\u00e9decins consid\u00e8rent maintenant qu\u2019une dose quotidienne de 1000-2000 UI de D3 est s\u00fbre et assurera des niveaux optimaux pour la plupart des adultes. Quant au moment de le prendre, car la vitamine est liposoluble, il sugg\u00e8re de l\u2019associer \u00e0 votre plus gros repas de la journ\u00e9e, \u00ab\u00a0contenant de la graisse pour assurer une absorption maximale\u00a0\u00bb. Mais encore une fois, v\u00e9rifiez avec votre m\u00e9decin avant de d\u00e9cider d\u2019essayer la vitamine D sous forme de suppl\u00e9ment.&nbsp;<\/p> ","protected":false},"excerpt":{"rendered":"<p>Vous savez d\u00e9j\u00e0 que la vitamine D est importante pour la sant\u00e9 des os, mais ses avantages ne s\u2019arr\u00eatent pas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[19],"tags":[],"class_list":["post-6861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nutrition"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"fr","enabled_languages":["en","es","de","fr","ru","hi","ar","tr","it","pt","na"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"na":{"title":false,"content":false,"excerpt":false}}},"featured_img":"https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/10\/Vitamin-D-and-Diabetes.jpg","categories_details":[{"id":19,"name":"Nutrition","count":205,"parent":0}],"tags_details":[],"comment_count":0,"author_name":"Staff","author_img":"https:\/\/secure.gravatar.com\/avatar\/0770ff71d5267ad67c1cefbf36008dc2a2753c332616ff451380094010b0d281?s=96&d=mm&r=g","post_views":6302,"_links":{"self":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/6861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/comments?post=6861"}],"version-history":[{"count":3,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/6861\/revisions"}],"predecessor-version":[{"id":16759,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/6861\/revisions\/16759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/media\/6862"}],"wp:attachment":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/media?parent=6861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/categories?post=6861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/tags?post=6861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}