{"id":6594,"date":"2024-09-02T00:00:53","date_gmt":"2024-09-02T00:00:53","guid":{"rendered":"https:\/\/fitolympia.com\/?p=6594"},"modified":"2024-09-02T17:08:44","modified_gmt":"2024-09-02T17:08:44","slug":"six-ways-to-lower-your-blood-pressure","status":"publish","type":"post","link":"https:\/\/fitolympia.com\/fr\/six-ways-to-lower-your-blood-pressure\/","title":{"rendered":"SIX FA\u00c7ONS D\u2019ABAISSER VOTRE TENSION ART\u00c9RIELLE"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ahchealthenewscdn.azureedge.net\/wp-content\/uploads\/2017\/02\/high-blood-pressure-505x336.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Les experts en sant\u00e9 cardiaque disent que l\u2019hypertension art\u00e9rielle est un tueur silencieux, offrant parfois peu de sympt\u00f4mes ext\u00e9rieurs avant que la trag\u00e9die ne puisse frapper.<\/p>\n\n\n\n<p>\u00ab&nbsp;De nombreux patients ne r\u00e9alisent pas qu\u2019ils ont une pression art\u00e9rielle \u00e9lev\u00e9e jusqu\u2019\u00e0 ce qu\u2019elle soit mesur\u00e9e, ou malheureusement au moment d\u2019une urgence, comme un accident vasculaire c\u00e9r\u00e9bral&nbsp;\u00bb, explique&nbsp;<a href=\"https:\/\/wexnermedical.osu.edu\/find-a-doctor\/jason-evanchan-do-30177\">Jason Evanchan,<\/a>DO, cardiologue au centre m\u00e9dical Wexner de l\u2019\u00c9tat de l\u2019Ohio.<\/p>\n\n\n\n<p>L\u2019hypertension est l\u2019un des principaux facteurs de risque de nombreux types de maladies cardiaques, y compris les crises cardiaques, l\u2019insuffisance cardiaque et les rythmes cardiaques anormaux tels que la fibrillation auriculaire, selon le Dr Evanchan. L\u2019hypertension est \u00e9galement un facteur de risque majeur pour le d\u00e9veloppement d\u2019une maladie r\u00e9nale.<\/p>\n\n\n\n<p>En d\u00e9pit d\u2019\u00eatre une telle condition commune mais potentiellement dangereuse, seulement la moiti\u00e9 des personnes diagnostiqu\u00e9es avec l\u2019hypertension art\u00e9rielle l\u2019ont sous un bon contr\u00f4le.<\/p>\n\n\n\n<p>Le Dr Evanchan a six conseils pour aider \u00e0 r\u00e9duire l\u2019hypertension art\u00e9rielle :<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1. Qu\u2019est-ce qui est normal \u2013 et l\u2019hypertension \u2013 pression art\u00e9rielle<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.heart.org\/-\/media\/images\/health-topics\/high-blood-pressure\/rainbow-chart\/blood-pressure-readings-chart.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>La premi\u00e8re \u00e9tape pour contr\u00f4ler l\u2019hypertension art\u00e9rielle est de comprendre les chiffres. La pression art\u00e9rielle est mesur\u00e9e en deux chiffres et en millim\u00e8tres de mercure. Le \u00ab&nbsp;premier&nbsp;\u00bb nombre, ou le premier, est la pression art\u00e9rielle systolique, ou la pression dans vos vaisseaux sanguins lorsque votre c\u0153ur bat. Le nombre \u00ab&nbsp;inf\u00e9rieur&nbsp;\u00bb, ou le second, est la pression art\u00e9rielle diastolique, qui mesure la pression dans vos vaisseaux sanguins entre les battements cardiaques.<\/p>\n\n\n\n<p>La pression art\u00e9rielle normale est une lecture systolique de moins de 120 mm Hg et une lecture diastolique de moins de 80 mm Hg.<\/p>\n\n\n\n<p>Suivez-nous sur Instagram @fitolympia1<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/09\/blood-1024x1024.png\" alt=\"\" class=\"wp-image-6595\" srcset=\"https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/09\/blood-1024x1024.png 1024w, https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/09\/blood-300x300.png 300w, https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/09\/blood-150x150.png 150w, https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/09\/blood-768x768.png 768w, https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/09\/blood-320x320.png 320w, https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/09\/blood.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>L\u2019hypertension art\u00e9rielle est une lecture systolique sup\u00e9rieure ou \u00e9gale \u00e0 130 mm Hg et \/ ou une lecture diastolique sup\u00e9rieure ou \u00e9gale \u00e0 80 mm Hg.Lorsque la pression art\u00e9rielle systolique est comprise entre 120 et 129 mm Hg, elle est consid\u00e9r\u00e9e comme une pression art\u00e9rielle \u00e9lev\u00e9e ou une pr\u00e9hypertension, ajoute le Dr Evanchan. Plus votre c\u0153ur pompe de sang et plus la r\u00e9sistance dans vos art\u00e8res est \u00e9lev\u00e9e, plus votre tension art\u00e9rielle sera \u00e9lev\u00e9e. L\u2019hypertension art\u00e9rielle peut endommager ou affaiblir vos vaisseaux sanguins, ce qui augmente le risque de caillots sanguins pouvant causer des crises cardiaques et des accidents vasculaires c\u00e9r\u00e9braux.<\/p>\n\n\n\n<p>\u00ab En g\u00e9n\u00e9ral, pour chaque 20 mm Hg plus \u00e9lev\u00e9 systolique et 10 mm Hg plus diastolique plus \u00e9lev\u00e9 que 115\/75 mm Hg, le risque de d\u00e9c\u00e8s par maladie cardiaque et accident vasculaire c\u00e9r\u00e9bral double \u00bb, dit le Dr Evanchan.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2. Surveillez votre tension art\u00e9rielle r\u00e9guli\u00e8rement<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cnet3.cbsistatic.com\/img\/PA-Zq-FsN7qsAk9RGhrJBmE9Qow=\/1200x675\/2019\/08\/02\/14e15472-8f58-4d0d-8e45-7dbbfb4fe590\/2.png\" alt=\"\"\/><\/figure>\n\n\n\n<p>Si vous \u00eates curieux de conna\u00eetre votre tension art\u00e9rielle et que vous souhaitez la v\u00e9rifier vous-m\u00eame, ou si votre m\u00e9decin vous a demand\u00e9 de la surveiller r\u00e9guli\u00e8rement, il existe des moyens de le faire \u00e0 l\u2019ext\u00e9rieur du cabinet du m\u00e9decin.<\/p>\n\n\n\n<p>\u00ab Des appareils de mesure ou des brassards sont disponibles dans de nombreuses pharmacies et sont recommand\u00e9s pour tout patient souffrant d\u2019hypertension art\u00e9rielle \u00bb, explique le Dr Evanchan.<\/p>\n\n\n\n<p>Notez les chiffres tous les jours sur une p\u00e9riode de quelques semaines et donnez-les \u00e0 votre m\u00e9decin.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3. Faites plus d\u2019exercice<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/learningworksforkids.com\/wp-content\/uploads\/kids_exercising.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Faire de l\u2019exercice r\u00e9guli\u00e8rement renforce le muscle cardiaque et l\u2019aide \u00e0 pomper avec moins d\u2019effort et moins de pression sur vos art\u00e8res. Souvent, l\u2019exercice physique r\u00e9gulier peut r\u00e9duire l\u2019hypertension art\u00e9rielle presque aussi efficacement que les m\u00e9dicaments.<\/p>\n\n\n\n<p>\u00ab Nous recommandons l\u2019exercice physique r\u00e9gulier et d\u2019intensit\u00e9 mod\u00e9r\u00e9e, dit le Dr Evanchan.<\/p>\n\n\n\n<p>Cela signifie environ 150 minutes par semaine d\u2019exercice ou pour 30 minutes, 5 jours par semaine. Le Dr Evanchan sugg\u00e8re de construire jusqu\u2019\u00e0 cela, m\u00eame en commen\u00e7ant \u00e0 seulement 60 minutes par semaine d\u2019exercice.<\/p>\n\n\n\n<p>La course, la marche, le v\u00e9lo et la natation sont d\u2019excellentes options d\u2019exercice qui peuvent aider \u00e0 r\u00e9duire la pression art\u00e9rielle au fil du temps.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4. Mangez moins de sodium et plus de potassium<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.health.harvard.edu\/media\/content\/images\/H0416_Salt_TSk-488081639.png\" alt=\"\"\/><\/figure>\n\n\n\n<p>Un r\u00e9gime riche en sodium rend plus difficile pour vos reins d\u2019\u00e9liminer l\u2019eau de votre circulation sanguine, ce qui augmente votre pression art\u00e9rielle et la pression sur vos vaisseaux sanguins en raison de l\u2019exc\u00e8s de liquide.<\/p>\n\n\n\n<p>C\u2019est pourquoi il est bon d\u2019\u00e9viter les aliments sal\u00e9s, tels que les charcuteries, les soupes en conserve, les condiments, les aliments congel\u00e9s et en bo\u00eete et les grignotines comme les croustilles et les bretzels sal\u00e9s, explique le Dr Evanchan.<\/p>\n\n\n\n<p>Un r\u00e9gime riche en potassium est id\u00e9al pour ceux qui ont une pression art\u00e9rielle \u00e9lev\u00e9e, car il diminue les effets du sodium sur le corps.<\/p>\n\n\n\n<p>\u00ab Le r\u00e9gime DASH \u2013 Approches di\u00e9t\u00e9tiques pour arr\u00eater l\u2019hypertension \u2013 par exemple, est une bonne option alimentaire, car il est riche en l\u00e9gumes, fruits, grains entiers, poisson, produits laitiers faibles en gras et noix \u00bb, dit le Dr Evanchan.<\/p>\n\n\n\n<p>Une alimentation plus saine peut \u00e9galement vous aider \u00e0 perdre du poids, ajoute le Dr Evanchan, ce qui peut \u00e0 son tour aider \u00e0 r\u00e9duire la pression art\u00e9rielle. Perdre aussi peu que cinq \u00e0 10 livres peut soulager l\u2019hypertension art\u00e9rielle.<br>&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5) R\u00e9duire le stress<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/3.bp.blogspot.com\/-Xg89NUQWge0\/VqkknEKtaxI\/AAAAAAAAB4g\/6TF0ITVfaYM\/s1600\/reduce%2Bstress.png\" alt=\"\"\/><\/figure>\n\n\n\n<p>Le stress augmente les hormones dans le sang qui font battre votre c\u0153ur plus rapidement et vos vaisseaux sanguins \u00e0 r\u00e9tr\u00e9cir. L\u2019hypertension art\u00e9rielle induite par le stress est g\u00e9n\u00e9ralement temporaire. Cependant, s\u2019il est associ\u00e9 \u00e0 une alimentation malsaine et \u00e0 un manque d\u2019exercice physique, le stress peut endommager de fa\u00e7on permanente vos vaisseaux, votre c\u0153ur et vos reins. Il est important de trouver des moyens de g\u00e9rer le stress afin que cela ne se produise pas.<\/p>\n\n\n\n<p>Pratiquer le yoga, la m\u00e9ditation et les exercices de respiration profonde; simplifier votre horaire; dormir beaucoup; et le maintien d\u2019une bonne alimentation et d\u2019un r\u00e9gime d\u2019exercice ont tous \u00e9t\u00e9 prouv\u00e9s pour r\u00e9duire le stress et l\u2019hypertension art\u00e9rielle.<\/p>\n\n\n\n<p>Le traitement de l\u2019apn\u00e9e du sommeil et l\u2019arr\u00eat du tabac sont deux \u00e9tapes suppl\u00e9mentaires pour soulager votre tension art\u00e9rielle.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">6) M\u00e9dicaments pour l\u2019hypertension art\u00e9rielle<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/post.healthline.com\/wp-content\/uploads\/sites\/3\/2020\/02\/321194_1100-1100x628.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>De nombreuses personnes souffrant d\u2019hypertension ont besoin de m\u00e9dicaments, en plus des changements de mode de vie, pour contr\u00f4ler leur tension art\u00e9rielle. En fait, avec les m\u00e9dicaments, l\u2019hypertension art\u00e9rielle peut \u00eatre contr\u00f4l\u00e9e rapidement, souvent en quelques jours. Il est tout aussi important de suivre la posologie et les instructions appropri\u00e9es avec les m\u00e9dicaments et de communiquer r\u00e9guli\u00e8rement avec votre m\u00e9decin.<\/p>\n\n\n\n<p>Les m\u00e9dicaments courants contre l\u2019hypertension art\u00e9rielle comprennent les diur\u00e9tiques (aider \u00e0 r\u00e9duire la quantit\u00e9 de sel et d\u2019eau dans le sang), les b\u00eata-bloquants (aident \u00e0 ralentir votre rythme cardiaque), les inhibiteurs des canaux calciques et les inhibiteurs de l\u2019eca (aident \u00e0 pr\u00e9venir le resserrement de vos vaisseaux sanguins).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les experts en sant\u00e9 cardiaque disent que l\u2019hypertension art\u00e9rielle est un tueur silencieux, offrant parfois peu de sympt\u00f4mes ext\u00e9rieurs avant [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[17],"tags":[],"class_list":["post-6594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-health"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"fr","enabled_languages":["en","es","de","fr","ru","hi","ar","tr","it","pt","na"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"na":{"title":false,"content":false,"excerpt":false}}},"featured_img":"https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/09\/bloodpressure_bloglarge.jpg","categories_details":[{"id":17,"name":"Health","count":260,"parent":0}],"tags_details":[],"comment_count":0,"author_name":"Staff","author_img":"https:\/\/secure.gravatar.com\/avatar\/0770ff71d5267ad67c1cefbf36008dc2a2753c332616ff451380094010b0d281?s=96&d=mm&r=g","post_views":6708,"_links":{"self":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/6594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/comments?post=6594"}],"version-history":[{"count":10,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/6594\/revisions"}],"predecessor-version":[{"id":15373,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/6594\/revisions\/15373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/media\/6596"}],"wp:attachment":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/media?parent=6594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/categories?post=6594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/tags?post=6594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}