{"id":14420,"date":"2025-05-08T00:00:03","date_gmt":"2025-05-08T00:00:03","guid":{"rendered":"https:\/\/fitolympia.com\/?p=14420"},"modified":"2025-05-08T18:07:57","modified_gmt":"2025-05-08T18:07:57","slug":"the-10-best-triceps-exercises-for-beginners","status":"publish","type":"post","link":"https:\/\/fitolympia.com\/fr\/the-10-best-triceps-exercises-for-beginners\/","title":{"rendered":"LES 10 MEILLEURS EXERCICES DE TRICEPS POUR LES D\u00c9BUTANTS"},"content":{"rendered":"<\/p>\n<p><em>Le secret des bras plus gros est de travailler \u00e0 la fois les bi et les tri.<\/em><\/p>\n<p>Lorsque la plupart des releveurs d\u00e9butants pensent \u00e0 construire leurs bras, les biceps semblent obtenir tout l\u2019amour. Et bien qu\u2019\u00eatre capable de faire \u00e9clater un pic impressionnant du haut du bras soit agr\u00e9able, la vraie magie de masse vient de faire des exercices de triceps.<\/p>\n<p>\u00ab\u00a0Les triceps sont le plus grand groupe musculaire du bras, occupant environ les deux tiers de la circonf\u00e9rence et formant la forme classique en fer \u00e0 cheval \u00e0 l\u2019arri\u00e8re du bras\u00a0\u00bb, explique\u00a0<a href=\"http:\/\/www.mikeclancytraining.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mike Clancy, C.S.C.S.,<\/a>un entra\u00eeneur personnel bas\u00e9 \u00e0 New York. \u00ab\u00a0Comme il y a trois t\u00eates (longues, lat\u00e9rales et m\u00e9diales) aux triceps, elles doivent \u00eatre stress\u00e9es avec une combinaison d\u2019angles, de volume et d\u2019intensit\u00e9, c\u2019est pourquoi la position du poignet, la position du coude et la position du bras peuvent changer consid\u00e9rablement lorsque l\u2019accent est mis sur le groupe musculaire des triceps.\u00a0\u00bb<\/p>\n<p>Ajoute\u00a0<em>La musculation sans blessure:<\/em>\u00a0\u00ab\u00a0De mani\u00e8re g\u00e9n\u00e9rale, vous devriez passer au moins la moiti\u00e9 de votre entra\u00eenement triceps \u00e0 entra\u00eener la longue t\u00eate, qui traverse l\u2019articulation de l\u2019\u00e9paule. Les exercices qui ciblent la longue t\u00eate ont g\u00e9n\u00e9ralement vos coudes pr\u00e8s de votre t\u00eate, comme les exercices a\u00e9riens.<\/p>\n<p>Lorsque vous d\u00e9marrez votre plan de triceps, vous souhaitez int\u00e9grer \u00e0 la fois des exercices de triceps lourds et des exercices \u00e0 volume \u00e9lev\u00e9. \u00ab\u00a0Les triceps ont besoin de beaucoup de stress &#8211; quatre s\u00e9ries de huit r\u00e9p\u00e9titions ne vont tout simplement pas le couper\u00a0\u00bb, dit Clancy. \u00ab\u00a0Un exerciseur doit viser \u00e0 accumuler au moins 100 r\u00e9p\u00e9titions au total dans les 30 minutes.\u00a0\u00bb<\/p>\n<p>Voici 10 mouvements de triceps classiques et \u00e9prouv\u00e9s que chaque releveur d\u00e9butant devrait conna\u00eetre.<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.muscleandfitness.com\/wp-content\/uploads\/2019\/12\/Chris-Bumstead-Doing-Skull-Crusher-With-Barbell-Weight.jpg?w=800&amp;quality=86&amp;strip=all\" alt=\"Professional bodybuilder Chris Bumstead working out his triceps with the barbell skull crusher exercise\" \/><\/figure>\n<h2>Broyeur de cr\u00e2ne<\/h2>\n<p>\u00ab\u00a0Cet exercice cible la longue t\u00eate des triceps, qui a tendance \u00e0 \u00eatre n\u00e9glig\u00e9e &#8211; c\u2019est donc l\u2019un de mes exercices d\u2019halt\u00e8res pr\u00e9f\u00e9r\u00e9s\u00a0\u00bb, explique Straub. \u00ab\u00a0Pour de meilleurs r\u00e9sultats, vos paumes devraient \u00eatre tourn\u00e9es vers vous et non vers vous, comme c\u2019est couramment le cas.\u00a0\u00bb<\/p>\n<p>Commencez ce mouvement classique de levage lourd en vous couchant sur le dos sur un banc, en saisissant un halt\u00e8re avec une poign\u00e9e serr\u00e9e juste au-dessus de votre front, les coudes pli\u00e9s de sorte que le haut des bras soit perpendiculaire au plafond. Avec le contr\u00f4le, redressez vos bras de sorte que le poids soit au-dessus de votre menton; puis pli\u00e9 pour revenir au d\u00e9but.<\/p>\n<p>2 SUR 10<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.muscleandfitness.com\/wp-content\/uploads\/2017\/09\/1109-triceps-pullover.jpg?w=800&amp;quality=86&amp;strip=all\" alt=\"Bodybuilder and fitness model doing a arms workout routine with the tricep exercises\" \/><\/figure>\n<h2>Pull-over Triceps<\/h2>\n<p>Comme le broyeur de cr\u00e2ne, ce mouvement commence derri\u00e8re la t\u00eate.<\/p>\n<p>\u00ab\u00a0Cet exercice est principalement destin\u00e9 \u00e0 \u00e9tirer les triceps (en particulier la longue t\u00eate), ce qui est une \u00e9tape n\u00e9cessaire pour un entra\u00eenement id\u00e9al des triceps\u00a0\u00bb, explique Straub, qui aime alterner cela avec le broyeur de cr\u00e2ne en sur-ensemble.<\/p>\n<p>3 SUR 10<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.muscleandfitness.com\/wp-content\/uploads\/2020\/02\/Female-In-Gym-Gear-Performing-Seated-Overhead-Tricep-Extension-Dumbbell.jpg?w=800&amp;quality=86&amp;strip=all\" alt=\"Fit female working out her upper body and arms with the tricep exercise the seated overhead dumbbell tricep extension\" \/><\/figure>\n<h2>Extension d\u2019halt\u00e8re a\u00e9rien assis<\/h2>\n<p>Un autre mouvement qui cible la longue t\u00eate, Straub sugg\u00e8re de faire un bras \u00e0 la fois pour les meilleurs r\u00e9sultats. Assis, saisissez un halt\u00e8re dans chaque main (ou un dans les deux), le haut des bras perpendiculaire au plafond, les coudes compl\u00e8tement pli\u00e9s. Redressez votre ou vos bras sans changer la position du haut de vos bras. Re-plier pour revenir au d\u00e9but.<\/p>\n<p>4 SUR 10<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.muscleandfitness.com\/wp-content\/uploads\/2018\/02\/Triceps-Kickback.jpg?w=650&amp;quality=86&amp;strip=all\" alt=\"Fitness model and bodybuilder working out his arms with a tricep exercises the tricep kickbac\" \/><\/figure>\n<h2>Triceps debout Pots-de-vin<\/h2>\n<p>\u00ab\u00a0C\u2019est l\u2019un de mes exercices pr\u00e9f\u00e9r\u00e9s pour les t\u00eates m\u00e9diales \/ lat\u00e9rales des triceps\u00a0\u00bb, dit Straub. D\u2019une position debout, tenez les halt\u00e8res \u00e0 vos c\u00f4t\u00e9s et charni\u00e8re \u00e0 la taille avec des genoux mous, comme si vous \u00eates au fond d\u2019un deadlift. Commencez avec le haut de vos bras parall\u00e8les \u00e0 votre torse et les bras pliants. Redressez vos bras et levez-les pour qu\u2019ils brisent le plan de votre dos. Revenez au d\u00e9but.<\/p>\n<p>5 SUR 10<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.muscleandfitness.com\/wp-content\/uploads\/2020\/02\/cable-overhead-triceps-extension.jpg?w=800&amp;quality=86&amp;strip=all\" alt=\"cable overhead triceps extension\" \/><\/figure>\n<h2>Extension de triceps a\u00e9riens de c\u00e2ble de c\u00e2ble<\/h2>\n<p>Ce mouvement, lorsqu\u2019il est fait correctement, \u00e9tire et renforce la longue t\u00eate du triceps, dit Straub. Soulevez le c\u00e2ble jusqu\u2019au sommet avec la corde \u00e0 double manche attach\u00e9e. Face \u00e0 la machine, attrapez la corde et la charni\u00e8re \u00e0 la taille, les bras pli\u00e9s et les mains derri\u00e8re la t\u00eate. Redressez vos bras le long de vos oreilles, en maintenant votre angle de torse. Re-pliez les bras avec le contr\u00f4le pour revenir au d\u00e9part.<\/p>\n<p>6 SUR 10<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.muscleandfitness.com\/wp-content\/uploads\/2020\/02\/Man-With-Muscular-Arms-Working-Out-And-Doing-Tricep-Exercises.jpg?w=800&amp;quality=86&amp;strip=all\" alt=\"man with muscular arms doing tricep exercises and workouts\" \/><\/figure>\n<h2>C\u00e2bles corde Triceps Pushdowns<\/h2>\n<p>Cet exercice cible les t\u00eates de triceps m\u00e9diales et lat\u00e9rales, ce qui le rend id\u00e9al pour surd\u00e9set avec l\u2019extension de triceps a\u00e9rien, dit Straub. R\u00e9glez toujours \u00e9lev\u00e9 vers le haut. Saisissez l\u2019une ou l\u2019autre extr\u00e9mit\u00e9 de la corde et r\u00e9glez votre coude \u00e0 angle droit, \u00e0 c\u00f4t\u00e9 de votre taille. Appuyez vos bras sur droit, amenant vos mains de chaque c\u00f4t\u00e9 de vos cuisses. Contr\u00f4le pour revenir \u00e0 la position de d\u00e9part.<\/p>\n<p>7 OF 10<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.muscleandfitness.com\/wp-content\/uploads\/2017\/07\/1109-triceps-dips-2.jpg?w=800&amp;quality=86&amp;strip=all\" alt=\"Muscular black man doing the bodyweight chest exercise the dip to build his chest muscles\" \/><\/figure>\n<h2>Trempettes<\/h2>\n<p>Ne le faites que si vous avez un bon contr\u00f4le de vos \u00e9paules &#8211; les trempettes mal faites peuvent causer une grave tension \u00e0 l\u2019\u00e9paule. Il est plus s\u00fbr de les faire avec une poign\u00e9e neutre sur les barres parall\u00e8les; les courts repose-sol sont pr\u00e9f\u00e9rables si vous avez besoin d\u2019avoir les pieds sur terre pour r\u00e9duire la charge.<\/p>\n<p>Saisissez les barres, les bras longs le long de votre torse, les \u00e9paules dans votre dos. (Si vous utilisez des barres basses, piquez \u00e0 la taille pour que vos jambes soient droites, en reposant sur vos talons devant vous.) Pliez vos coudes derri\u00e8re vous et appuyez pour revenir \u00e0 droite.<\/p>\n<p>8 OF 10<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.muscleandfitness.com\/wp-content\/uploads\/2019\/06\/Close-Grip-Bench-Juan-Morales.jpg?w=800&amp;quality=86&amp;strip=all\" alt=\"Bodybuilder Juan Morales working out his chest with a close grip barbell bench press exercise\" \/><\/figure>\n<h2>D\u00e9velopp\u00e9 couch\u00e9 \u00e0 poign\u00e9e rapproch\u00e9e<\/h2>\n<p>Oui, cet exercice \u00ab\u00a0poitrine\u00a0\u00bb est \u00e9galement id\u00e9al pour les tri. L\u2019astuce pour travailler vos triceps plus fort est de garder le haut de vos bras serr\u00e9s dans le torse.<\/p>\n<p>\u00c0 l\u2019aide d\u2019un halt\u00e8re ou d\u2019halt\u00e8res, allongez-vous sur le dos sur un banc, avec les coudes le long de vos c\u00f4t\u00e9s. Appuyez tout droit vers le haut, poids au-dessus des pecs, puis abaissez jusqu\u2019\u00e0 la position de d\u00e9part.<\/p>\n<p>9 OF 10<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.muscleandfitness.com\/wp-content\/uploads\/2019\/10\/Man-With-Beard-Doing-Half-Pushup.jpg?w=800&amp;quality=86&amp;strip=all\" alt=\"Fit man with a beard doing a bodyweight workout and doing a half rep pushup exercise\" \/><\/figure>\n<h2>Pompes<\/h2>\n<p>La poitrine re\u00e7oit une aide majeure des triceps dans ce mouvement du haut du corps de r\u00e9f\u00e9rence, surtout si vous gardez votre position de la main pr\u00e8s de la poitrine et tirez vos coudes droit vers l\u2019arri\u00e8re plut\u00f4t que de les torcher sur les c\u00f4t\u00e9s. Pensez \u00e0 lancer votre poitrine vers l\u2019avant pour vraiment mettre le fardeau sur vos tris.<\/p>\n<p>10 OF 10<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.muscleandfitness.com\/wp-content\/uploads\/2017\/09\/1109-dive-bomber-yoga-upward-dog.jpg?w=800&amp;quality=86&amp;strip=all\" alt=\"Fitness couple doing dive bomber yoga pose\" \/><\/figure>\n<h2>Bombardiers en piqu\u00e9<\/h2>\n<p>Consid\u00e9rez celui-ci \u00ab\u00a0d\u00e9butant avanc\u00e9\u00a0\u00bb. Ce pushup modifi\u00e9 fait que les triceps travaillent dur pour stabiliser le corps. \u00c0 partir de la position haute de la planche, piquez vos hanches vers le haut, puis pliez vos coudes en arri\u00e8re pendant que vous tangez la t\u00eate vers le bas et vers l\u2019avant, comme si vous plongeiez sous une barri\u00e8re basse. Appuyez sur vos bras directement pour revenir au sommet.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>Le secret des bras plus gros est de travailler \u00e0 la fois les bi et les tri. Lorsque la plupart [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[220,140],"tags":[],"class_list":["post-14420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exercises","category-training-tips"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"fr","enabled_languages":["en","es","de","fr","ru","hi","ar","tr","it","pt","na"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"na":{"title":false,"content":false,"excerpt":false}}},"featured_img":"https:\/\/fitolympia.com\/wp-content\/uploads\/2021\/07\/Chris-Bumstead-Doing-Skull-Crusher-With-Barbell-Weight.jpg","categories_details":[{"id":220,"name":"Exercises","count":40,"parent":0},{"id":140,"name":"Training Tips","count":97,"parent":0}],"tags_details":[],"comment_count":0,"author_name":"Staff","author_img":"https:\/\/secure.gravatar.com\/avatar\/0770ff71d5267ad67c1cefbf36008dc2a2753c332616ff451380094010b0d281?s=96&d=mm&r=g","post_views":20941,"_links":{"self":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/14420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/comments?post=14420"}],"version-history":[{"count":10,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/14420\/revisions"}],"predecessor-version":[{"id":14523,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/posts\/14420\/revisions\/14523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/media\/14423"}],"wp:attachment":[{"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/media?parent=14420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/categories?post=14420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fitolympia.com\/fr\/wp-json\/wp\/v2\/tags?post=14420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}