{"id":6276,"date":"2024-05-02T00:00:46","date_gmt":"2024-05-02T00:00:46","guid":{"rendered":"https:\/\/fitolympia.com\/?p=6276"},"modified":"2024-05-02T16:37:54","modified_gmt":"2024-05-02T16:37:54","slug":"7-foods-to-boost-your-workout","status":"publish","type":"post","link":"https:\/\/fitolympia.com\/es\/7-foods-to-boost-your-workout\/","title":{"rendered":"7 ALIMENTOS PARA AUMENTAR TU ENTRENAMIENTO"},"content":{"rendered":"<\/p>\n<p>Se proyecta que la industria de suplementos y nutrici\u00f3n deportiva alcanzar\u00e1 m\u00e1s de $6 mil millones para 2018. Sin embargo, muchos nutrientes en estos productos comercializados a atletas de todas las capacidades se encuentran m\u00e1s convenientemente en los alimentos naturales. Muchos alimentos y bebidas se han demostrado en la investigaci\u00f3n para proporcionar beneficios \u00fanicos para el crecimiento muscular, reducir la inflamaci\u00f3n o proporcionar energ\u00eda r\u00e1pida necesaria para los entrenamientos.<\/p>\n<p>Una dieta alta en frutas y verduras puede proporcionar una rica fuente de antioxidantes que protegen a las c\u00e9lulas del da\u00f1o causado por el ejercicio, y obtener el equilibrio adecuado de carbohidratos saludables, grasas y prote\u00ednas tambi\u00e9n puede proporcionar energ\u00eda sostenida y bloques de construcci\u00f3n para la s\u00edntesis de prote\u00ednas.<\/p>\n<h2>Jugo de cereza tarta<\/h2>\n<p>Los atletas, ya sean profesionales o reci\u00e9n comenzando, pueden tener una mayor necesidad de antioxidantes porque el ejercicio puede aumentar la cantidad de da\u00f1o causado por los radicales libres.<\/p>\n<p>Los investigadores recomiendan (<strong><a href=\"http:\/\/ajcn.nutrition.org\/content\/72\/2\/637s.full\" target=\"_blank\" rel=\"noreferrer noopener\">1<\/a><\/strong>) para obtener estos antioxidantes necesarios de los alimentos sobre suplementos.<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.caloriesecrets.net\/wp-content\/uploads\/2016\/09\/cherry-juice.jpg\" alt=\"foods to boost your workout\" \/><\/figure>\n<p>El jugo de cereza tarta es una rica fuente de antioxidantes y se ha demostrado en algunas investigaciones para ayudar a los m\u00fasculos de los atletas a recuperarse m\u00e1s r\u00e1pido despu\u00e9s del ejercicio.<\/p>\n<p>Los polifenoles en el jugo de cereza agria pueden ayudar a reducir la inflamaci\u00f3n, el estr\u00e9s y el da\u00f1o asociados con el entrenamiento de fuerza o\u00a0<strong>correr a larga distancia<\/strong>\u00a0(<strong><a href=\"http:\/\/www.choosecherries.com\/health-and-nutrition\/recovery\/\" target=\"_blank\" rel=\"noreferrer noopener\">2<\/a><\/strong>).<\/p>\n<p>Un estudio de 2011 concluy\u00f3 que el jugo de cereza de tarta mejor\u00f3 la\u00a0<strong>recuperaci\u00f3n de los m\u00fasculos<\/strong>\u00a0despu\u00e9s del entrenamiento de fuerza en comparaci\u00f3n con los participantes a los que se les administr\u00f3 un placebo.<\/p>\n<p>\u00bfCu\u00e1nto jugo de cereza agria necesitas para ayudar a tus m\u00fasculos?<\/p>\n<p>La mayor\u00eda de los estudios con jugo de cereza agria y rendimiento del ejercicio utilizaron la cantidad de personas que beben 2 porciones de 8 o 12 onzas por d\u00eda de jugo de cereza agria.<\/p>\n<p>El jugo de cereza dulce no ha demostrado el mismo beneficio del jugo de cereza agria con el ejercicio.<\/p>\n<p>Beber jugo de cereza justo antes de un entrenamiento duro puede no beneficiar su entrenamiento de inmediato, pero podr\u00eda ayudar a sus m\u00fasculos a recuperarse mejor para que sus entrenamientos al d\u00eda siguiente pueden ser mejores.<\/p>\n<h2>Jugo de remolacha<\/h2>\n<p>Otro jugo que muestra la promesa de ayudar con el rendimiento del ejercicio es el jugo de remolacha.<\/p>\n<p>El jugo de remolacha es una rica fuente de nitratos, que si se toma justo antes del ejercicio intenso puede ayudar a los m\u00fasculos a usar ox\u00edgeno de manera m\u00e1s eficiente durante el ejercicio.<\/p>\n<p>Un estudio de 2011 encontr\u00f3 que el jugo de remolacha ayud\u00f3 a los ciclistas a aumentar su potencia en una carrera contrarreloj. Los participantes ingirieron alrededor de 2 tazas de jugo de remolacha 2 horas antes de la contrarreloj.<\/p>\n<p>No todos los estudios han demostrado un beneficio con el jugo de remolacha y el rendimiento del ejercicio, por lo que se necesita m\u00e1s investigaci\u00f3n.<\/p>\n<p>Parece que el jugo de remolacha puede ser m\u00e1s beneficioso cuando se consume constantemente y para ejercicios m\u00e1s cortos y de alta intensidad.<\/p>\n<p>El sabor del jugo de remolacha puede ser poco atractivo, as\u00ed que si quieres probarlo intenta mezclarlo en un batido primero.<\/p>\n<h2>Semillas de ch\u00eda<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"alignright\"><img decoding=\"async\" class=\"wp-image-2979\" src=\"https:\/\/www.caloriesecrets.net\/wp-content\/uploads\/2014\/02\/health-benefits-chia-seeds.jpg\" alt=\"health-benefits-chia-seeds\" \/><\/figure>\n<\/div>\n<p><strong><a href=\"https:\/\/www.caloriesecrets.net\/five-health-benefits-of-chia-seeds\/\">Las semillas de ch\u00eda<\/a>\u00a0<\/strong>eran un elemento b\u00e1sico en las antiguas culturas maya y azteca y por una buena raz\u00f3n.<\/p>\n<p>Las semillas de ch\u00eda son una rica fuente de todos los amino\u00e1cidos esenciales, fibra, omega 3, hierro, calcio y magnesio.<\/p>\n<p>Si bien no hay investigaciones sustanciales que indiquen que las semillas de ch\u00eda podr\u00edan proporcionar ning\u00fan beneficio adicional para el rendimiento del ejercicio, son una fuente compacta de muchos nutrientes que los ejercitadores necesitan especialmente omega 3. Tambi\u00e9n pueden proporcionar energ\u00eda sostenida sin causar grandes oscilaciones en el az\u00facar en la sangre.<\/p>\n<p>Una palabra de precauci\u00f3n con las semillas de chai: son altas en fibra. Comer demasiados antes del ejercicio podr\u00eda causar cierta angustia gastrointestinal. Absorben el agua, por lo que deben consumirse con suficiente l\u00edquido.<\/p>\n<p>De hecho, una manera f\u00e1cil de obtener algunas semillas de ch\u00eda en su dieta es agregar una cucharada o dos a su botella de agua y beber durante todo el d\u00eda.<\/p>\n<p>Las semillas de ch\u00eda tambi\u00e9n se pueden espolvorear en ensaladas, yogur, avena o simplemente comerse de forma normal.<\/p>\n<h2>Bayas<\/h2>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.dictionary.com\/e\/wp-content\/uploads\/2018\/09\/berries_1000x700.jpg\" alt=\"\" \/><\/figure>\n<p>Todas las bayas son una rica fuente de antioxidantes, vitaminas y minerales que pueden beneficiar el rendimiento del ejercicio.\u00a0<strong>Las bayas<\/strong>\u00a0y otras frutas y verduras son especialmente altas en vitamina C.<\/p>\n<p>Comer una gran cantidad de bayas tambi\u00e9n puede ayudar a preservar la masa muscular.<\/p>\n<p>Un estudio de\u00a0<em>la Universidad de Pittsburgh<\/em>\u00a0encontr\u00f3 que los adultos mayores que ten\u00edan una mayor ingesta de vitamina C y E diet\u00e9tica ten\u00edan mayor preservaci\u00f3n muscular m\u00e1s adelante en la vida.<\/p>\n<p>Los investigadores no est\u00e1n seguros de si la vitamina C y E ayudan a preservar el m\u00fasculo o si una mayor ingesta de C y E se asocia con una dieta m\u00e1s saludable sobre todo.<\/p>\n<h2>Pl\u00e1tanos<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"alignright\"><img decoding=\"async\" class=\"wp-image-4205\" src=\"https:\/\/www.caloriesecrets.net\/wp-content\/uploads\/2015\/07\/health-benefits-of-banana-300x178.jpg\" alt=\"health benefits of bananas\" \/><\/figure>\n<\/div>\n<p>El humilde pl\u00e1tano es f\u00e1cil de digerir y una fuente r\u00e1pida de combustible de carbohidratos para hacer ejercicio.<\/p>\n<p>Con s\u00f3lo unas\u00a0<strong><a href=\"https:\/\/www.caloriesecrets.net\/top-eight-health-benefits-of-bananas\/\">100 calor\u00edas para un pl\u00e1tano mediano,<\/a><\/strong>puede hacer un refrigerio f\u00e1cil y nutritivo antes, durante o despu\u00e9s de un entrenamiento.<\/p>\n<p>Los pl\u00e1tanos son una fuente natural del potasio electrol\u00edtico que desempe\u00f1a un papel en el equilibrio de fluidos, la contracci\u00f3n muscular y nerviosa.<\/p>\n<p>Tener niveles adecuados de electrolitos y l\u00edquidos en el cuerpo tambi\u00e9n puede ayudar a prevenir calambres musculares.<\/p>\n<p>Se pueden combinar con mantequilla de nuez, a\u00f1adirse a un batido o comer como un aperitivo ligeramente dulce en cualquier momento.<\/p>\n<h2>Nueces\/ mantequillas de nueces<\/h2>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/s3.amazonaws.com\/img.mynetdiary.com\/blog\/are-you-including-nut-butter-in-your-weight-loss-plan-are-nut-butters-healthy.jpeg\" alt=\"\" \/><\/figure>\n<p>Un poco va un largo camino con nueces y mantequillas de nueces. Emparejarlos con una fuente de carbohidratos como fruta o pan puede proporcionar un equilibrio constante de energ\u00eda, prote\u00ednas y grasas saludables que pueden ayudarte a sostenerte a trav\u00e9s de un entrenamiento.<\/p>\n<p>Las nueces tambi\u00e9n son altas en hierro, B6,\u00a0<strong>potasio<\/strong>\u00a0y magnesio.<\/p>\n<p>El hierro es importante para la entrega adecuada de ox\u00edgeno a los m\u00fasculos, B6 se utiliza para convertir los alimentos en energ\u00eda para las c\u00e9lulas, potasio es importante para la contracci\u00f3n muscular y la regulaci\u00f3n de fluidos y magnesio es importante para la salud \u00f3sea y la producci\u00f3n de energ\u00eda.<\/p>\n<h2>Leche de chocolate<\/h2>\n<p>\u00bfQu\u00e9 tiene de bueno la leche de chocolate? Tiene un equilibrio especial de carbohidratos y prote\u00ednas que se considera la proporci\u00f3n \u00f3ptima despu\u00e9s del ejercicio para reconstruir el m\u00fasculo.<\/p>\n<p>Muchos estudios han demostrado un beneficio de la leche de chocolate despu\u00e9s del ejercicio en la protecci\u00f3n del m\u00fasculo del da\u00f1o.<\/p>\n<p>Por ejemplo, un estudio de 2012 (<strong><a href=\"https:\/\/europepmc.org\/abstract\/med\/21904247\" target=\"_blank\" rel=\"noreferrer noopener\">5<\/a><\/strong>) encontr\u00f3 que la s\u00edntesis de prote\u00ednas musculares se increment\u00f3 y la descomposici\u00f3n de prote\u00ednas enteras del cuerpo fue menor en sujetos que ingirieron leche de chocolate en comparaci\u00f3n con una bebida de carbohidratos despu\u00e9s de una carrera de resistencia en una cinta de correr.<\/p>\n<p>Si tienes entrenamientos dobles en un d\u00eda, beber leche de chocolate despu\u00e9s de un entrenamiento agotado puede ayudar a tus m\u00fasculos a repostar despu\u00e9s de la primera sesi\u00f3n de ejercicio y ayudarte a ir m\u00e1s tiempo en tu pr\u00f3xima pelea de ejercicios m\u00e1s tarde en el d\u00eda seg\u00fan un estudio de 2008.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>Se proyecta que la industria de suplementos y nutrici\u00f3n deportiva alcanzar\u00e1 m\u00e1s de $6 mil millones para 2018. Sin embargo, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6277,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[54,231,17],"tags":[],"class_list":["post-6276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-fruits","category-health"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"es","enabled_languages":["en","es","de","fr","ru","hi","ar","tr","it","pt","na"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"na":{"title":false,"content":false,"excerpt":false}}},"featured_img":"https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/09\/N.jpg","categories_details":[{"id":54,"name":"General","count":104,"parent":0},{"id":231,"name":"Fruits","count":59,"parent":0},{"id":17,"name":"Health","count":260,"parent":0}],"tags_details":[],"comment_count":0,"author_name":"Staff","author_img":"https:\/\/secure.gravatar.com\/avatar\/0770ff71d5267ad67c1cefbf36008dc2a2753c332616ff451380094010b0d281?s=96&d=mm&r=g","post_views":6703,"_links":{"self":[{"href":"https:\/\/fitolympia.com\/es\/wp-json\/wp\/v2\/posts\/6276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitolympia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fitolympia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/es\/wp-json\/wp\/v2\/comments?post=6276"}],"version-history":[{"count":10,"href":"https:\/\/fitolympia.com\/es\/wp-json\/wp\/v2\/posts\/6276\/revisions"}],"predecessor-version":[{"id":17271,"href":"https:\/\/fitolympia.com\/es\/wp-json\/wp\/v2\/posts\/6276\/revisions\/17271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/es\/wp-json\/wp\/v2\/media\/6277"}],"wp:attachment":[{"href":"https:\/\/fitolympia.com\/es\/wp-json\/wp\/v2\/media?parent=6276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fitolympia.com\/es\/wp-json\/wp\/v2\/categories?post=6276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fitolympia.com\/es\/wp-json\/wp\/v2\/tags?post=6276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}