{"id":6530,"date":"2024-05-25T00:00:01","date_gmt":"2024-05-25T00:00:01","guid":{"rendered":"https:\/\/fitolympia.com\/?p=6530"},"modified":"2024-05-25T17:27:30","modified_gmt":"2024-05-25T17:27:30","slug":"repetition-maximum-for-weight-training","status":"publish","type":"post","link":"https:\/\/fitolympia.com\/de\/repetition-maximum-for-weight-training\/","title":{"rendered":"WIEDERHOLUNGSMAXIMUM F\u00dcR KRAFTTRAINING"},"content":{"rendered":"<\/p>\n<p id=\"mntl-sc-block_1-0\"><span>Ein Wiederholungsmaximum (RM) ist das meiste Gewicht, das Sie f\u00fcr eine definierte Anzahl von \u00dcbungsbewegungen heben k\u00f6nnen. Zum Beispiel w\u00e4re ein 10RM das schwerste Gewicht, das Sie f\u00fcr 10 aufeinanderfolgende \u00dcbungswiederholungen heben k\u00f6nnten. Ihr RM ist ein gutes Ma\u00df f\u00fcr Ihr aktuelles St\u00e4rkeniveau<\/span><sup>1<\/sup><span>\u00a0wenn Sie Ihrem Krafttrainingsprogramm folgen.<\/span><\/p>\n<h2 id=\"mntl-sc-block_1-0-2\">Maximal eine Wiederholung oder 1RM<\/h2>\n<p id=\"mntl-sc-block_1-0-3\">Das Wiederholungsmaximum wird oft als 1RM- oder Ein-Wiederholungsmaximum ausgedr\u00fcckt. Dies zeigt das schwerste Gewicht an, das Sie mit maximaler Anstrengung in einer einzigen Wiederholung heben k\u00f6nnen. Ein 1RM ist Ihr pers\u00f6nlicher Gewichtheberrekord f\u00fcr eine Kniebeuge, Kreuzheben oder eine andere Gewichtheber\u00fcbung.<\/p>\n<p id=\"mntl-sc-block_1-0-5\"><span>Die 1RM-Messung ist ein Standard im Krafttraining zur Verbesserung der Markierung.<\/span><sup>1<\/sup><span>\u00a0Indem Sie Ihr 1RM einrichten und verfolgen, k\u00f6nnen Sie Ihren Fortschritt beobachten. Es ist ein pr\u00e4zises Ma\u00df, so dass es Ihnen helfen kann, zu beurteilen, wie effektiv Ihr Programm ist. Au\u00dferdem erhalten Sie positive Verst\u00e4rkung und ein Erfolgserlebnis, wenn Sie eine M\u00f6glichkeit haben, Verbesserungen klar zu sehen.<\/span><\/p>\n<h2 id=\"mntl-sc-block_1-0-7\">So testen Sie Ihren 1RM sicher<\/h2>\n<p id=\"mntl-sc-block_1-0-8\">W\u00e4hrend 1RM ein sehr n\u00fctzliches Werkzeug ist, hat es Einschr\u00e4nkungen. Das Messen Ihres 1RM ist nicht nur eine Frage des gr\u00f6\u00dften Gewichts und der Durchf\u00fchrung einer Wiederholung. Per Definition werden Sie diesen Muskel maximal belasten und sich dem Risiko einer Verletzung aussetzen, wenn Sie es nicht richtig machen. Sie m\u00fcssen sich darauf vorbereiten, es richtig zu machen.<\/p>\n<p id=\"mntl-sc-block_1-0-10\"><span>Bevor Sie Ihre 1RM messen, f\u00fchren Sie ein paar Aufw\u00e4rms\u00e4tze der \u00dcbung durch, um den Muskel vorzubereiten.<\/span><sup>1<\/sup><span>\u00a0Ein aufgew\u00e4rmter Muskel ist weitaus seltener verletzt. Das Aufw\u00e4rmen mag zeitaufwendig erscheinen, ist aber unerl\u00e4sslich.<\/span><\/p>\n<p id=\"mntl-sc-block_1-0-12\">Planen Sie auch vierundzwanzig Stunden Ruhezeit f\u00fcr einen Muskel ein, bevor Sie einen 1RM-Test durchf\u00fchren. F\u00fchren Sie diesen Test nicht am Nachmittag durch, wenn Sie ein morgendliches Training der gleichen Muskelgruppe hatten.<\/p>\n<p id=\"mntl-sc-block_1-0-14\">Verwenden Sie schlie\u00dflich immer einen Spotter. Selbst bei einem richtigen Aufw\u00e4rmen ist das Verletzungsrisiko aufgrund des hohen Gewichts, das Sie verwenden, hoch. Ein Spotter ist unerl\u00e4sslich, um Verletzungen zu vermeiden.<\/p>\n<h3 id=\"mntl-sc-block-callout-heading_1-0\">Testen Sie Ihre 1RM: Schritt f\u00fcr Schritt<\/h3>\n<ol>\n<li>W\u00e4hlen Sie, welche Bewegung Sie testen m\u00f6chten (Kniebeuge, Bankdr\u00fccken usw.).<\/li>\n<li>W\u00e4rmen Sie sich mit leichter Cardio-Aktivit\u00e4t und dynamischem Stretching f\u00fcr mindestens 15 bis 30 Minuten auf.<\/li>\n<li>Machen Sie sechs bis 10 Wiederholungen Ihrer gew\u00e4hlten Bewegung mit einem Gewicht, das etwa die H\u00e4lfte dessen ist, was Sie denken, dass Ihr Maximum sein wird. Dann ruhen Sie sich mindestens ein bis zwei Minuten aus.<\/li>\n<li>Erh\u00f6hen Sie das Gewicht auf bis zu 80% von dem, was Sie denken, dass Ihr Maximum sein k\u00f6nnte. Machen Sie drei Wiederholungen und ruhen Sie sich dann mindestens eine Minute aus.<\/li>\n<li>F\u00fcgen Sie das Gewicht in Etwa 10%-Schritten hinzu und versuchen Sie jedes Mal eine einzelne Wiederholung, wobei Sie zwischen jedem Versuch mindestens ein bis zwei Minuten ruhen.<\/li>\n<li>Das maximale Gewicht, das Sie mit guter Form und Technik erfolgreich heben k\u00f6nnen, ist Ihr 1RM.<\/li>\n<\/ol>\n<p id=\"mntl-sc-block_1-0-18\">Es gibt auch submaximale Testmethoden, die verwendet werden k\u00f6nnen, um 1RM anzun\u00e4hern. Diese k\u00f6nnen sicherer sein, sind aber m\u00f6glicherweise nicht so genau.<\/p>\n<h2 id=\"mntl-sc-block_1-0-20\">RM in \u00dcbungsanweisungen<\/h2>\n<p id=\"mntl-sc-block_1-0-21\">Sie werden sehen, dass das Wiederholungsmaximum in \u00dcbungsanweisungen verwendet wird. Zum Beispiel w\u00fcrde &#8220;drei S\u00e4tze von 6RM-Lifts&#8221; bedeuten, jede \u00dcbung mit dem Gewicht durchzuf\u00fchren, das Sie nur mit guter Form sechsmal heben k\u00f6nnen. Sie w\u00fcrden alle \u00dcbungen ausf\u00fchren und dann die Sequenz zwei weitere Male wiederholen (insgesamt drei S\u00e4tze).<\/p>\n<p id=\"mntl-sc-block_1-0-23\">Es ist auch \u00fcblich, Anweisungen f\u00fcr Gewichte zu sehen, die auf einem Prozentsatz von 1RM basieren, z. B. &#8220;Sechs Wiederholungen bei 75% von 1RM&#8221;. Wenn Ihr 1RM 20 Pfund f\u00fcr diese \u00dcbung ist, w\u00fcrden Sie 15 Pfund Gewicht verwenden, wenn Sie diese Anweisungen befolgen.<\/p>\n<p id=\"mntl-sc-block_1-0-25\">Durch die Verwendung von Wiederholungsmaximum anstelle von definierten Gewichten k\u00f6nnen Menschen mit unterschiedlichen F\u00e4higkeiten Trainingsanweisungen verwenden (eine Person w\u00fcrde beispielsweise 10-Pfund-Gewichte verwenden, w\u00e4hrend eine andere 30-Pfund-Gewichte verwenden w\u00fcrde). Sie w\u00fcrden jeweils von dem Trainingseffekt profitieren, den die \u00dcbungssequenz erzeugen sollte. Plus, wenn Sie Ihre Kraft verbessern, k\u00f6nnen Sie weiterhin die gleichen Anweisungen verwenden, aber schwerere Gewichte verwenden.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Wiederholungsmaximum (RM) ist das meiste Gewicht, das Sie f\u00fcr eine definierte Anzahl von \u00dcbungsbewegungen heben k\u00f6nnen. Zum Beispiel w\u00e4re [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6531,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[55,140],"tags":[],"class_list":["post-6530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gym-fitness","category-training-tips"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"de","enabled_languages":["en","es","de","fr","ru","hi","ar","tr","it","pt","na"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"na":{"title":false,"content":false,"excerpt":false}}},"featured_img":"https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/09\/The-5-Most-Dangerous-Deadlift-Mistakes.jpg","categories_details":[{"id":55,"name":"Gym Fitness","count":46,"parent":0},{"id":140,"name":"Training Tips","count":97,"parent":0}],"tags_details":[],"comment_count":0,"author_name":"Staff","author_img":"https:\/\/secure.gravatar.com\/avatar\/0770ff71d5267ad67c1cefbf36008dc2a2753c332616ff451380094010b0d281?s=96&d=mm&r=g","post_views":6349,"_links":{"self":[{"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/posts\/6530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/comments?post=6530"}],"version-history":[{"count":10,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/posts\/6530\/revisions"}],"predecessor-version":[{"id":14289,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/posts\/6530\/revisions\/14289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/media\/6531"}],"wp:attachment":[{"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/media?parent=6530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/categories?post=6530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/tags?post=6530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}