{"id":6178,"date":"2024-01-01T15:23:57","date_gmt":"2024-01-01T15:23:57","guid":{"rendered":"https:\/\/fitolympia.com\/?p=6178"},"modified":"2024-01-01T15:24:11","modified_gmt":"2024-01-01T15:24:11","slug":"squats-the-proper-technique-benefits-and-variations","status":"publish","type":"post","link":"https:\/\/fitolympia.com\/de\/squats-the-proper-technique-benefits-and-variations\/","title":{"rendered":"Kniebeugen \u2013 die richtige Technik, Vorteile und Variationen"},"content":{"rendered":"<p>Die grundlegendsten und beliebtesten \u00dcbungen f\u00fcr&nbsp;<strong>Tonisierende Beine und Hintern sind definitiv Kniebeugen.<\/strong>&nbsp;Diese fehlen sicherlich nicht w\u00e4hrend einer&nbsp;<strong>&#8220;Leg Day&#8221;<\/strong>&nbsp;von jedem Liebhaber des Gewichthebens. Aber sind Sie sicher, dass Sie es sind?<strong>&nbsp;sie richtig machen?<\/strong>&nbsp;Wei\u00dft du&nbsp;<strong>alle Arten von Kniebeugen<\/strong>&nbsp;mit dem Sie<strong>&nbsp;Ihr Training beleben?<\/strong>&nbsp;Welche anderen&nbsp;<strong>Bringt diese \u00dcbung Vorteile mit sich?<\/strong>&nbsp;Die Antworten auf diese und weitere Fragen zu Kniebeugen finden Sie im folgenden Artikel.<\/p> <h2 class=\"wp-block-heading\">Was sind Kniebeugen?<\/h2> <p>Kniebeugen sind eine der besten<strong>&nbsp;funktionelle \u00dcbungen zur St\u00e4rkung der unteren K\u00f6rperteile.<\/strong>&nbsp;Mit ihrer richtigen Technik,&nbsp;<strong>Sie werden Ihre Beine, Ihren Hintern, aber auch Ihre Bauchmuskeln oder den Kern Ihres K\u00f6rpers bearbeiten.<\/strong>&nbsp;Ihr Vorteil ist jedoch, dass sie&nbsp;<strong>kann jederzeit und \u00fcberall durchgef\u00fchrt werden,<\/strong>&nbsp;ohne spezielle Ausr\u00fcstung. Ihre falsche Technik&nbsp;ist jedoch<strong>kann einige unangenehme Verletzungen verursachen.<\/strong><\/p> <p>Wenn wir uns auf Kniebeugen in Bezug auf ihre Verwendung konzentrieren w\u00fcrden, w\u00fcrden Sie feststellen, dass Sie\u00a0<strong>fast die ganze Zeit in die Hocke gehen.<\/strong>\u00a0Wenn Ihre Schl\u00fcssel fallen und Sie sich b\u00fccken, um sie zu erreichen, oder wenn Sie die Schn\u00fcrsenkel an Ihren Schuhen binden m\u00f6chten,\u00a0<strong>Du machst eine bestimmte Art von Kniebeuge.<\/strong>\u00a0Die einzige\u00a0<strong>Unterschied zwischen diesen Aktionen<\/strong>\u00a0und echte Kniebeugen sind, dass, wenn Sie hocken,\u00a0<strong>Sie konzentrieren sich bewusst auf die richtige Haltung und Muskelst\u00e4rkung.<\/strong> <\/p> <figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/gymbeam.sk\/blog\/wp-content\/uploads\/2020\/07\/82993053_2646076925514004_687855745646985216_o-min-1124x794.jpg\" alt=\"Squats - the proper technique, benefits and variations\" class=\"wp-image-176644\" title=\"Squats - the proper technique, benefits and variations\"\/><\/figure> <h2 class=\"wp-block-heading\">Welche Muskeln besch\u00e4ftigen Sie beim Hocken?<\/h2> <p>Kniebeugen sind in erster Linie darauf ausgelegt,\u00a0<strong>St\u00e4rken Sie die Beinmuskulatur und den Po.<\/strong>\u00a0Dank der richtigen Haltung w\u00e4hrend ihrer Leistung und\u00a0<strong>mehrere Variationen von Kniebeugen,<\/strong>\u00a0Sie k\u00f6nnen\u00a0<strong>Engagieren Sie viel mehr Muskeln.<\/strong> <\/p> <p>W\u00e4hrend einer Standard-Kniebeuge mit Ihrem eigenen Gewicht engagieren Sie:<\/p> <ul class=\"wp-block-list\"><li>quadriceps thigh muscle<\/li><li>hamstrings<\/li><li>quads<\/li><li>abductors<\/li><li>butt<\/li><li>straight abdominal muscle<\/li><li>biceps calf muscle<\/li><\/ul> <p>Wenn Sie Gewichte beim Hocken verwenden oder andere Variationen des Hockens ausprobieren, k\u00f6nnen Sie auch die Muskeln von:<\/p> <ul class=\"wp-block-list\"><li>back<\/li><li>forearm<\/li><li>shoulders<\/li><li>external and internal abdominal muscles<\/li><li>triceps<\/li><li>biceps<\/li><\/ul> <figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/gymbeam.sk\/blog\/wp-content\/uploads\/2020\/07\/DSC00007-min-1124x751.jpg\" alt=\"What muscles do you engage during squatting?\" class=\"wp-image-176618\" title=\"What muscles do you engage during squatting?\"\/><\/figure> <h2 class=\"wp-block-heading\">Die richtige Technik, um eine Kniebeuge zu machen<\/h2> <p>Die richtige Squat-Technik hilft\u00a0<strong>Maximieren Sie Ihre Bem\u00fchungen<\/strong>\u00a0und verhindern\u00a0<strong>unangenehme Verletzungen oder Muskelschmerzen.<\/strong>\u00a0Wie geht das?<\/p> <ol class=\"wp-block-list\"><li>Stand upright and spread your legs hip-width apart \u2013 toes facing forward.<\/li><li>Push your shoulders back slightly and squeeze your abdomen.<\/li><li>Stretch your shoulders or put your hands on your sides.<\/li><li>Inhale, slowly lower yourself to the floor, bend your knees and push your butt back a little.<\/li><li>Keep your back straight, do not bend it.<\/li><li>Stop when you reach the squat position with your knees bent at a 90\u00b0 angle and your thighs parallel to the floor \u2013 stay in this position for about 2 seconds.<\/li><li>Push on your heels, slowly straighten up your legs, and return to an upright position with an exhale.<\/li><li>For the best squat effect, repeat the exercise at least 10 to 15 times in a row.<\/li><\/ol> <p>F\u00fcr ein noch besseres Verst\u00e4ndnis der\u00a0<strong>richtige Hocktechnik,<\/strong>\u00a0Sehen Sie sich das Anleitungsvideo an:<\/p> <figure class=\"wp-block-embed-youtube wp-block-embed is-type-rich is-provider-embed-handler wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe loading=\"lazy\" title=\"Bowflex\u00ae How-To | Squats for Beginners\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/aclHkVaku9U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure> <h2 class=\"wp-block-heading\">Die h\u00e4ufigsten Fehler bei einer Kniebeuge<\/h2> <ul class=\"wp-block-list\"><li><strong>You do not go low enough to the floor\u00a0<\/strong>\u2013 with the right squat technique, your thighs should be parallel to the floor. However, if you do not go low enough and do not reach this point, you will not fully engage all the necessary muscles.<\/li><li><strong>Switching knees\u00a0<\/strong>\u2013 a very common problem when performing a squat. Not only does this make it impossible to do a squat properly, but it also puts a lot of unnecessary load on your knees. This can damage your joints and tendons.<\/li><li><strong>You do not put your knees apart\u00a0<\/strong>\u2013 when lifting from a squat, the knees should point outwards, not inwards. When you point your knees inwards, you will make it easier to squat, but then squatting makes no sense.<\/li><li><strong>Crouching\u00a0<\/strong>\u2013 When squatting, it is extremely important to keep your back upright, otherwise it may lead to an injury. You should therefore avoid bending it or creasing it.<\/li><li><strong>You lift your heels off the floor\u00a0<\/strong>\u2013 standing up from the squat should be accompanied by the pressure of the heels. This is because if you push your heels into the floor, you will ensure safe and correct muscle activation and balance. Therefore, never stand on tiptoe when lifting from a squat, but transfer all your weight to the heels.<\/li><\/ul> <h2 class=\"wp-block-heading\">Vorteile von Kniebeugen<\/h2> <p>Kniebeugen nicht nur\u00a0<strong>st\u00e4rken Ihre Muskeln,<\/strong>\u00a0aber sie verstecken sich auch\u00a0<strong>Viele weitere Vorteile.<\/strong>\u00a0Indem Sie sie ausf\u00fchren, k\u00f6nnen Sie auch viele grundlegende Aktivit\u00e4ten verbessern, z. B.\u00a0<strong>Gehen, Sitzen oder Heben und Tragen schwerer Lasten.<\/strong>\u00a0Aber das ist definitiv noch nicht alles! Finden Sie heraus, welche anderen\u00a0<strong>Vorteile, die Sie erhalten, wenn Sie regelm\u00e4\u00dfig Kniebeugen machen.<\/strong> <\/p> <ul class=\"wp-block-list\"><li>support proper posture<\/li><li>help burn calories \u2013 an approximately 64-kilo person can burn up to 133 calories in 15 minutes of intense squatting<\/li><li>improve flexibility and stability<\/li><li>strengthen the lungs and heart<\/li><li>help prevent injuries<\/li><li>maintain joint health<\/li><li>maintain strong bones<\/li><li>improve movement speed<\/li><li>improve digestion and blood circulation in the body<\/li><\/ul> <figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/gymbeam.sk\/blog\/wp-content\/uploads\/2020\/07\/72321269_2440264779428554_2345617773629014016_o-min-1124x750.jpg\" alt=\"Squats with Weights\" class=\"wp-image-176657\" title=\"Squats with Weights\"\/><\/figure> <h2 class=\"wp-block-heading\">Squat Variationen<\/h2> <p>Es gibt\u00a0<strong>unz\u00e4hlige von ihnen.<\/strong>\u00a0Dank mehrerer Variationen der Kniebeuge\u00a0<strong>Sie werden auch andere wichtige Muskeln in der \u00dcbung aktivieren<\/strong> <strong>und beleben Sie Ihr Training.<\/strong>\u00a0Denken Sie jedoch daran, dass Sie, wenn Sie neu im Training und in der Hocke sind,<strong>\u00a0sich darauf konzentrieren, die richtige Technik einer grundlegenden Kniebeuge zu verstehen,<\/strong>\u00a0und dann versuchen Sie es mit anderen,\u00a0<strong>anspruchsvollere Formen<\/strong>\u00a0davon. Sie k\u00f6nnen auch verschiedene Tools verwenden, z. B.\u00a0<strong>Hanteln, Widerstandsb\u00e4nder und Expander, Kettlebells, ein Stuhl oder ein Balance-Pad.<\/strong>\u00a0Schauen Sie sich an, welche Arten von Kniebeugen Sie in Ihren Trainingsplan integrieren k\u00f6nnen.<\/p> <h3 class=\"wp-block-heading\">Bulgarische Kniebeugen<\/h3> <p>Bevor Sie bulgarische Kniebeugen durchf\u00fchren, m\u00fcssen Sie sich vorbereiten&nbsp;<strong>ein \u00dcbungswerkzeug,<\/strong>&nbsp;was ist&nbsp;<strong>ein Schritt,<\/strong>&nbsp;<strong>ein niedrigerer Stuhl oder eine Bank.<\/strong>&nbsp;Stehen Sie mit dem R\u00fccken zur Stufe und&nbsp;<strong>Beugen Sie Ihren rechten Fu\u00df<\/strong>&nbsp;damit Sie<strong>&nbsp;Legen Sie die Oberseite Ihres Fu\u00dfes auf die Stufe.<\/strong>&nbsp;Dies wird Ihr&nbsp;<strong>Ausgangsstellung.<\/strong>&nbsp;Biegen Sie dann die&nbsp;<strong>linkes Bein am Knie und in einer Hockbewegung auf den Boden ziehen<\/strong>&nbsp;bis das Knie des rechten Beines fast den Boden ber\u00fchrt. Stelle sicher&nbsp;<strong>Ihre Schultern sind nach hinten gerichtet, Ihr R\u00fccken ist gerade,<\/strong>&nbsp;Und Sie stehen beim Heben nicht auf den Zehenspitzen. Wenn Sie diese \u00dcbung erschweren m\u00f6chten, k\u00f6nnen Sie dies tun, w\u00e4hrend&nbsp;<strong>Hanteln halten.<\/strong><\/p> <figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/gymbeam.sk\/blog\/wp-content\/uploads\/2020\/07\/94380042_2861684403953254_2446104524998311936_o-min-749x1124.jpg\" alt=\"Bulgarian Squats\" class=\"wp-image-176631\" title=\"Bulgarian Squats\"\/><\/figure> <figure class=\"wp-block-embed-youtube wp-block-embed is-type-rich is-provider-embed-handler wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe loading=\"lazy\" title=\"Bulgarian Split Squat...You&#039;re Doing It Wrong\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Ksz5rkmBuTA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure> <h3 class=\"wp-block-heading\">Sumo Kniebeugen<\/h3> <p>Die Breite Ihrer Beine w\u00e4hrend dieser Art von Kniebeuge sollte sein<strong>\u00a0etwas gr\u00f6\u00dfer<\/strong>\u00a0als w\u00e4hrend einer klassischen Kniebeuge. Stehen Sie also aufrecht, damit Ihre Beine\u00a0<strong>Etwas weiter auseinander als die Breite Ihrer Schultern.<\/strong>\u00a0Zehen sollten zeigen\u00a0<strong>leicht nach au\u00dfen.<\/strong>\u00a0Dr\u00fccken Sie Ihre H\u00fcften und Schultern nach hinten,\u00a0<strong>Halten Sie Ihren R\u00fccken gerade<\/strong>\u00a0und senken Sie sich in die Kniebeuge. Stoppen Sie nur, wenn\u00a0<strong>Ihre H\u00fcften sind etwas unter dem Niveau Ihrer Knie.<\/strong><\/p> <figure class=\"wp-block-embed-youtube wp-block-embed is-type-rich is-provider-embed-handler wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe loading=\"lazy\" title=\"How to do Sumo Squats\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/sqDGkIBYPAk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure> <h3 class=\"wp-block-heading\"><strong>Kniebeuge auf der Smith Machine<\/strong><\/h3> <p><strong>Smith-Maschine<\/strong>, oder sogenannte Multipress, ist ein ausgezeichnetes Werkzeug f\u00fcr jeden, der eine\u00a0<strong>Problem beim Hocken und Aufrechterhalten eines geraden R\u00fcckens.<\/strong>\u00a0Diese Maschine wartet immer\u00a0<strong>eine Flugbahn der Bewegung,<\/strong>\u00a0Von dem Sie sicherlich nicht abweichen werden. Es ist eine\u00a0<strong>Klassische Kniebeugentechnik, aber mit einem Gewicht<\/strong>\u00a0auf Ihre Fallen gelegt. Seien Sie jedoch vorsichtig\u00a0<strong>nicht auf Zehenspitzen zu stehen<\/strong>\u00a0aufgrund des Gewichts an der Ausgangsposition oder\u00a0<strong>umgekehrt, nicht in einer Kniebeugungsposition zu sein.<\/strong>\u00a0Passen Sie das Gewicht so an, dass Sie das Gef\u00fchl haben\u00a0<strong>komfortabel und sicher<\/strong>\u00a0beim Training.<\/p> <figure class=\"wp-block-embed-youtube wp-block-embed is-type-rich is-provider-embed-handler wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe loading=\"lazy\" title=\"HOW TO SQUAT ON THE SMITH MACHINE\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/DUWK_gKcRCc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure> <h3 class=\"wp-block-heading\">Kniebeugen mit Gewichten<\/h3> <p>Sobald Sie&nbsp;<strong>Beherrschen Sie die grundlegende Hocktechnik<\/strong>&nbsp;mit dem eigenen Gewicht ist es an der Zeit&nbsp;,<strong>F\u00fcgen Sie etwas Eisen hinzu!<\/strong>&nbsp;Es gibt mehrere M\u00f6glichkeiten, dies zu tun. Sie k\u00f6nnen entweder hinzuf\u00fcgen&nbsp;<strong>Hanteln, Kettlebell oder Langhantel,<\/strong>&nbsp;in die Kniebeuge. Achten Sie bei der Verwendung von Hanteln darauf, dass ihr Gewicht&nbsp;<strong>dr\u00fcckt dich nicht automatisch mehr mit deiner Brust zu Boden.<\/strong>&nbsp;Wenn Sie die Langhantel auf dem R\u00fccken verwenden, achten Sie darauf, dass Sie es nicht mit der Waage \u00fcbertreiben und<strong>&nbsp;Verursachen Sie sich Verletzungen.<\/strong><\/p> <figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/gymbeam.sk\/blog\/wp-content\/uploads\/2020\/07\/TC300052-min-749x1124.jpg\" alt=\"Squats with Weights\" class=\"wp-image-176605\" title=\"Squats with Weights\"\/><\/figure> <figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe loading=\"lazy\" title=\"The Back Squat\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ultWZbUMPL8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure> <h3 class=\"wp-block-heading\"><strong>\u00dcberkopf-Kniebeugen<\/strong><\/h3> <p>Zus\u00e4tzlich zu den unteren Teilen Ihres K\u00f6rpers wird diese Variante der Kniebeuge auch&nbsp;<strong>Ihr Kern und die Muskeln des R\u00fcckens, der Schultern und der Arme.<\/strong><\/p> <p>Die Ausgangsposition der Kniebeuge ist\u00a0<strong>das gleiche wie bei der klassischen Kniebeuge,<\/strong>\u00a0aber wir behalten unsere H\u00e4nde\u00a0<strong>aufrecht \u00fcber unseren K\u00f6pfen.<\/strong>\u00a0Um diese \u00dcbung zu erschweren, f\u00fcgen Sie Gewichte in Form einer Langhantel, Kettlebell oder eines Gymnastikballs hinzu.<\/p> <figure class=\"wp-block-embed-youtube wp-block-embed is-type-rich is-provider-embed-handler wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe loading=\"lazy\" title=\"The Overhead Squat\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/pn8mqlG0nkE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure> <h3 class=\"wp-block-heading\"><strong>Kniebeugensprung<\/strong><\/h3> <p>Es ist eine<strong>\u00a0plyometrische Bewegung,<\/strong>\u00a0was eigentlich bedeutet, dass<strong>\u00a0Sie f\u00fchren Aerobic-\u00dcbungen durch<\/strong>\u00a0mit dieser Art von Kniebeuge. Sie verlangt daher, dass\u00a0<strong>Sie machen so viele Bewegungen wie m\u00f6glich in k\u00fcrzester Zeit.<\/strong>\u00a0Die Technik eines Kniebeugensprungs ist<strong>\u00a0identisch mit der klassischen Kniebeuge,<\/strong>\u00a0aber beim Anheben vom Boden\u00a0<strong>Du dr\u00fcckst ein wenig mehr mit deinen Fersen und springst heraus.<\/strong>\u00a0Wir empfehlen, dieser Art von Kniebeuge nur dann Gewichte hinzuzuf\u00fcgen, wenn\u00a0<strong>Sie haben diese Technik wirklich gemeistert.<\/strong><\/p> <figure class=\"wp-block-embed-youtube wp-block-embed is-type-rich is-provider-embed-handler wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe loading=\"lazy\" title=\"WORKOUT TECHNIQUE | How to safely do a Squat Jump?\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/72BSZupb-1I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure> <h3 class=\"wp-block-heading\"><strong>Wandsitz<\/strong><\/h3> <p>Stehen Sie zu Ihrem\u00a0<strong>Zur\u00fcck zur Wand<\/strong>\u00a0und bewegen Sie sich langsam in die gedrungene Position.\u00a0<strong>Ihr R\u00fccken und Kopf m\u00fcssen die Wand jederzeit ber\u00fchren<\/strong>. Langsam\u00a0<strong>Bewegen Sie Ihre Beine von der Wand weg<\/strong>\u00a0erschaffen\u00a0<strong>eine grundlegende Hockposition<\/strong>\u00a0\u2013 Ihre Knie sind in einem 90 \u00b0 -Winkel gebeugt, Ihre Zehen zeigen nach vorne und Ihre Oberschenkel sind parallel zum Boden. Sie sollten<strong>\u00a0Bleiben Sie mindestens eine Minute in dieser Position.<\/strong>\u00a0Sie k\u00f6nnen\u00a0<strong>Legen Sie eine Langhantel oder Kettlebell auf die Knie<\/strong>\u00a0um diese \u00dcbung zu erschweren. Obwohl es sich nicht um eine\u00a0<strong>dynamische Art der Kniebeuge,<\/strong>\u00a0es wird auf jeden Fall\u00a0<strong>Fordern Sie Ihre Oberschenkelmuskulatur und Ihren Hintern heraus.<\/strong><\/p> <figure class=\"wp-block-embed-youtube wp-block-embed is-type-rich is-provider-embed-handler wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe loading=\"lazy\" title=\"How to Do a Wall Sit | Thighs Workout\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/XULOKw4E4P4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure> <h3 class=\"wp-block-heading\"><strong>Seitlicher Hockweg<\/strong><\/h3> <p>Wieder einmal ein\u00a0<strong>aerobe Art von Kniebeuge.<\/strong>\u00a0Stehen Sie im\u00a0<strong>Ausgangslage einer klassischen Kniebeuge<\/strong>\u00a0und bewegen Sie sich langsam nach unten. Aber\u00a0<strong>in dieser Position bleiben,<\/strong>\u00a0heben Sie nicht an, sondern\u00a0<strong>Machen Sie mit dem rechten Fu\u00df einen Schritt zur Seite.<\/strong>\u00a0Stellen Sie sicher, dass Ihre Oberschenkel w\u00e4hrend dieser Bewegung noch auf der gleichen H\u00f6he sind. Dann\u00a0<strong>Wiederholen Sie die gleiche Bewegung mit dem linken Fu\u00df<\/strong>\u00a0Sodass\u00a0<strong>Sie kommen zur\u00fcck in die Hockposition.<\/strong>\u00a0Sie k\u00f6nnen die Bewegung wiederholen<strong>\u00a0mehrere Male mehr auf eine Seite<\/strong>\u00a0und tauschen Sie dann die Seiten. Sie k\u00f6nnen auch eine<strong>\u00a0Widerstandsband oder ein Expander<\/strong>\u00a0um es schwieriger zu machen, in die Hocke zu gehen.<\/p> <figure class=\"wp-block-embed-youtube wp-block-embed is-type-rich is-provider-embed-handler wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/youtube.com\/watch?v=yrSBgbjLbog\n<\/div><\/figure> <h3 class=\"wp-block-heading\"><strong>Einbeinige Kniebeuge<\/strong><\/h3> <p>Eine ideale Kniebeuge f\u00fcr\u00a0<strong>die bestm\u00f6gliche \u00dcbung von Oberschenkelmuskulatur und Po,<\/strong>\u00a0aber auch zu\u00a0<strong>eine bessere Stabilit\u00e4t zu erreichen.<\/strong>\u00a0Nehmen Sie die\u00a0<strong>Ausgangsstellung<\/strong>\u00a0eines<strong>\u00a0klassische Kniebeuge<\/strong>\u00a0Und dann\u00a0<strong>Strecken Sie ein Bein vor sich.<\/strong>\u00a0Bewegen Sie sich langsam nach unten, in die Hockposition. Sie k\u00f6nnen<strong>\u00a0Strecken Sie Ihre Arme aus<\/strong>\u00a0um die bestm\u00f6gliche Balance zu erreichen. Halten Sie Ihren Fu\u00df\u00a0<strong>immer noch ausgestreckt.<\/strong>\u00a0Einfach so viel kauern\u00a0<strong>wie dein K\u00f6rper dich gehen l\u00e4sst.<\/strong>\u00a0Wechseln Sie nicht die Knie und versuchen Sie,\u00a0<strong>Aufrechterhaltung der bestm\u00f6glichen Stabilit\u00e4t.<\/strong><\/p> <figure class=\"wp-block-embed-youtube wp-block-embed is-type-rich is-provider-embed-handler wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe loading=\"lazy\" title=\"Single-Leg Squat - Glute Strengthening Exercises for Runners\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/9_Ca2YRRdtE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure> <h3 class=\"wp-block-heading\"><strong>Pli\u00e9 Squat<\/strong><\/h3> <p>Die beste Art von Kniebeuge f\u00fcr<strong>\u00a0Ihre Beine straffen,<\/strong>\u00a0deren Technik\u00a0<strong>\u00dcberhaupt nicht \u00e4hnlich wie der klassische.<\/strong>\u00a0Nehmen Sie eine\u00a0<strong>Position wie bei einer Sumo-Kniebeuge<\/strong>\u00a0mit einer breiteren Position,\u00a0<strong>Spreizen oder strecken Sie Ihre Arme<\/strong>\u00a0und bewege dich in Richtung Kniebeuge. W\u00e4hrend einer Pli\u00e9-Kniebeuge hingegen ist Ihr Gewicht<strong>\u00a0bleibt nicht auf den Fersen, sondern verschiebt sich auf die Zehen.<\/strong>\u00a0Stellen Sie sich daher mit Ihren Kniebeugen auf die Zehen und\u00a0<strong>Dr\u00fccken Sie Ihre Knie auseinander<\/strong>\u00a0damit Sie das Gef\u00fchl haben\u00a0<strong>So viel Druck wie m\u00f6glich auf die innere Oberschenkelmuskulatur.<\/strong>\u00a0Diese vom Ballett inspirierte Kniebeuge ist\u00a0<strong>Besonders beliebt bei Frauen.<\/strong><\/p> <figure class=\"wp-block-embed-youtube wp-block-embed is-type-rich is-provider-embed-handler wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe loading=\"lazy\" title=\"How to do Pli\u00e9 Squats to Tone Your Legs | Health\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/FPeq0s4jDxw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure> <p>Nat\u00fcrlich<strong>\u00a0Es gibt viele Variationen von Kniebeugen,<\/strong>\u00a0Deshalb haben wir uns f\u00fcr die<strong>\u00a0Top am einfachsten und beliebtesten f\u00fcr Sie.<\/strong>\u00a0Was ist mit dir und Kniebeugen?\u00a0<strong>Beziehen Sie sie in Ihren Trainingsplan ein?<\/strong>\u00a0Welche Art von Kniebeuge machst du?<strong>\u00a0Wie am besten?<\/strong> <\/p> ","protected":false},"excerpt":{"rendered":"<p>Die grundlegendsten und beliebtesten \u00dcbungen f\u00fcr&nbsp;Tonisierende Beine und Hintern sind definitiv Kniebeugen.&nbsp;Diese fehlen sicherlich nicht w\u00e4hrend einer&nbsp;&#8220;Leg Day&#8221;&nbsp;von jedem Liebhaber [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[202,55,139],"tags":[],"class_list":["post-6178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-benefits","category-gym-fitness","category-muscle-building"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"de","enabled_languages":["en","es","de","fr","ru","hi","ar","tr","it","pt","na"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"na":{"title":false,"content":false,"excerpt":false}}},"featured_img":"https:\/\/fitolympia.com\/wp-content\/uploads\/2020\/09\/squats.jpg","categories_details":[{"id":202,"name":"Benefits","count":165,"parent":0},{"id":55,"name":"Gym Fitness","count":46,"parent":0},{"id":139,"name":"Muscle Building","count":53,"parent":0}],"tags_details":[],"comment_count":0,"author_name":"Staff","author_img":"https:\/\/secure.gravatar.com\/avatar\/0770ff71d5267ad67c1cefbf36008dc2a2753c332616ff451380094010b0d281?s=96&d=mm&r=g","post_views":7196,"_links":{"self":[{"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/posts\/6178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/comments?post=6178"}],"version-history":[{"count":3,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/posts\/6178\/revisions"}],"predecessor-version":[{"id":17113,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/posts\/6178\/revisions\/17113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/media\/6191"}],"wp:attachment":[{"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/media?parent=6178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/categories?post=6178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/tags?post=6178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}