{"id":15050,"date":"2023-04-04T17:28:02","date_gmt":"2023-04-04T17:28:02","guid":{"rendered":"https:\/\/fitolympia.com\/?p=15050"},"modified":"2023-04-04T17:28:04","modified_gmt":"2023-04-04T17:28:04","slug":"whats-the-difference-between-micronutrients-and-macronutrients","status":"publish","type":"post","link":"https:\/\/fitolympia.com\/de\/whats-the-difference-between-micronutrients-and-macronutrients\/","title":{"rendered":"WAS IST DER UNTERSCHIED ZWISCHEN MIKRON\u00c4HRSTOFFEN UND MAKRON\u00c4HRSTOFFEN?"},"content":{"rendered":"\n<p>Makron\u00e4hrstoffe und Mikron\u00e4hrstoffe sind Kategorien, die Ern\u00e4hrungsberater und Ern\u00e4hrungsexperten verwenden k\u00f6nnen, um sich auf Ihre Ern\u00e4hrung zu beziehen.<\/p>\n\n\n\n<p>Makron\u00e4hrstoffe sind gro\u00dfe Ern\u00e4hrungskategorien wie Kohlenhydrate, Fette und Proteine. Mikron\u00e4hrstoffe sind kleinere N\u00e4hrstoffkategorien, wie einzelne Vitamine und Mineralstoffe wie Kalzium, Zink und Vitamin B-6.<\/p>\n\n\n\n<p>Vielleicht haben Sie irgendwann den Ausdruck &#8220;Makros z\u00e4hlen&#8221; geh\u00f6rt. Dies bezieht sich auf einen Di\u00e4tansatz, bei dem eine Person versucht, einen bestimmten Prozentsatz an Kalorien aus jeder Makron\u00e4hrstoffgruppe zu essen.<\/p>\n\n\n\n<p>Lesen Sie weiter, um mehr \u00fcber die Forschung zu erfahren, die f\u00fcr diesen Ern\u00e4hrungsansatz verf\u00fcgbar ist, und wie einige Leute ihn einsetzen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mikros vs. Makros<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/ErfqMmXu8Gk\/maxresdefault.jpg\" alt=\"\"\/><figcaption>&#8216;<\/figcaption><\/figure>\n\n\n\n<p>Der Anfang jedes Wortes gibt Ihnen einen kleinen Hinweis darauf, was sie bedeuten k\u00f6nnen. &#8220;Makro&#8221; kommt vom griechischen Wort&nbsp;<em>makros<\/em>, was gro\u00df bedeutet.<\/p>\n\n\n\n<p>Ern\u00e4hrungsphysiologisch gesehen werden Makros in der Regel in Gramm gemessen, wie z.B. Gramm Fett oder Proteine. Viele makrobasierte Di\u00e4ten klassifizieren Makron\u00e4hrstoffe auf drei Arten:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Kohlenhydrate:<\/strong>&nbsp;enthalten in Lebensmitteln wie Brot, Nudeln und Fr\u00fcchten, die 4 Kalorien pro Gramm liefern<\/li><li><strong>Fette:&nbsp;<\/strong>enthalten in Lebensmitteln wie \u00d6len, N\u00fcssen und Fleisch, die 9 Kalorien pro Gramm liefern<\/li><li><strong>Protein:&nbsp;<\/strong>gefunden in Lebensmitteln wie Eiern, Fisch und Tofu, die 4 Kalorien pro Gramm liefern<\/li><\/ul>\n\n\n\n<p>Beachten Sie, dass einige Di\u00e4ten Alkohol als eigenen Makron\u00e4hrstoff klassifizieren, der 7 Kalorien pro Gramm hat. Da Alkohol jedoch im Vergleich zu den anderen drei Kategorien nur einen sehr geringen N\u00e4hrwert hat, enthalten einige Di\u00e4ten ihn nicht.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i2.wp.com\/stayfitmom.com\/wp-content\/uploads\/2021\/01\/micros-vs-macros-1.png?fit=560%2C315\" alt=\"\"\/><\/figure>\n\n\n\n<p>Mikros sind viel kleinere Messwerte in Bezug auf die Ern\u00e4hrung. &#8220;Micro&#8221; kommt vom griechischen Wort&nbsp;<em>mikros,<\/em>&nbsp;was klein bedeutet. Sie messen die meisten&nbsp;<strong>Mikron\u00e4hrstoffe&nbsp;<\/strong>in Milligramm oder sogar Mikrogramm.<\/p>\n\n\n\n<p>Es gibt viele Mikron\u00e4hrstoffe in den Lebensmitteln, die Sie essen, insbesondere Obst und Gem\u00fcse, die reich an Vitaminen und Mineralien sind. Beispiele f\u00fcr Mikron\u00e4hrstoffe umfassen, sind aber nicht beschr\u00e4nkt auf:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Kalzium<\/li><li>folat<\/li><li>Eisen<\/li><li>Vitamin B-6<\/li><li>Vitamin B-12<\/li><li>Ascorbins\u00e4ure<\/li><li>Vitamin E<\/li><li>Zink<\/li><\/ul>\n\n\n\n<p>Die meisten Makron\u00e4hrstoffe enthalten unterschiedliche Mikron\u00e4hrstoffe. Die meisten Menschen w\u00fcrden jedoch keinen Mikron\u00e4hrstoffansatz f\u00fcr Di\u00e4ten verwenden, da es schwierig w\u00e4re, sie zu messen und zu verfolgen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wie es funktioniert<\/h2>\n\n\n\n<p>Menschen k\u00f6nnen verschiedene Ans\u00e4tze in Bezug auf die t\u00e4glichen Makron\u00e4hrstoffe verwenden. Zum Beispiel gibt die&nbsp;<a href=\"https:\/\/health.gov\/dietaryguidelines\/2015\/resources\/2015-2020_dietary_guidelines.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Dietary Guidelines for AmericansTrusted Source<\/a>&nbsp;die folgenden Empfehlungen in Bezug auf Makron\u00e4hrstoffkategorien:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>45 bis 65 Prozent der Kalorien aus Kohlenhydraten<\/li><li>20 bis 35 Prozent der Kalorien aus Fett<\/li><li>10 bis 35 Prozent der Kalorien aus Protein<\/li><\/ul>\n\n\n\n<p>Eine Person, die Makros als di\u00e4tetischen Ansatz z\u00e4hlt, w\u00fcrde zuerst berechnen, wie viel Energie sie jeden Tag in Form von Kalorien ben\u00f6tigt. Dann w\u00fcrden sie entscheiden, wie viel Prozent der Kalorien aus jeder Lebensmittelgruppe sie basierend auf ihren Zielen essen w\u00fcrden.<\/p>\n\n\n\n<p>Zum Beispiel essen Bodybuilder, die Muskeln aufbauen m\u00f6chten, normalerweise h\u00f6here Anteile an Protein, einem Muskelbaustein. Diejenigen, die ihren Blutzucker genau beobachten, k\u00f6nnen Kohlenhydrate auf dem niedrigeren Prozentsatz essen, weil sie versuchen, ihren Blutzucker zu halten.<\/p>\n\n\n\n<p>Die meisten wissenschaftlichen Forschungen in Bezug auf Makron\u00e4hrstoffe beinhalten die Verfolgung der Ern\u00e4hrung einer Person und die Zerlegung in Makron\u00e4hrstoffe. Dies unterscheidet sich davon, eine Person zu bitten, einer bestimmten Menge an Makron\u00e4hrstoffen zu folgen und zu sehen, ob sie Abnehmen oder andere Ziele erreichen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Beliebte Di\u00e4ten<\/h2>\n\n\n\n<p>Mehrere beliebte Di\u00e4ten verwenden einen makrobasierten Ansatz oder eine Form davon. Dazu geh\u00f6ren:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Wenn es zu Ihrer Makros (IIFYM) Di\u00e4t passt<\/li><li>ketogene (Keto) Di\u00e4t<\/li><li>Paleo-Di\u00e4t<\/li><li>Weight Watchers<\/li><\/ul>\n\n\n\n<p>W\u00e4hrend einige dieser Di\u00e4ten sich nicht explizit als Makrodi\u00e4t bezeichnen, beinhalten sie das Essen einer bestimmten Portion jeder Lebensmittelgruppe. Makrodi\u00e4ten sind solche, die die Portionskontrolle betonen und eine Vielzahl von Lebensmitteln essen, anstatt Kalorien zu z\u00e4hlen.<\/p>\n\n\n\n<p>Einige Ern\u00e4hrungsexperten nennen Makrodi\u00e4ten &#8220;flexible Di\u00e4ten&#8221;, weil sie Kalorien oder Lebensmittel nicht einschr\u00e4nken, sondern nur eine Person anleiten, welche Lebensmittelarten mehr oder weniger zu essen sind.<\/p>\n\n\n\n<p>Diese Di\u00e4ten k\u00f6nnen Ihnen helfen, eine Reihe von Gesundheitszielen zu erreichen, wie z. B. den Aufbau von Muskelmasse, das Abnehmen, eine ges\u00fcndere Ern\u00e4hrung, die Aufrechterhaltung des Blutzuckerspiegels und vieles mehr.<\/p>\n\n\n\n<p>Es ist wichtig zu beachten, dass eine Makrodi\u00e4t nicht dasselbe ist wie eine makrobiotische Di\u00e4t. Die makrobiotische Ern\u00e4hrung stammt aus Japan und basiert auf Prinzipien der traditionellen chinesischen Medizin. Es legt Wert darauf, einfache, biologische und lokale Lebensmittel zu essen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ist es echt oder Hype?<\/h2>\n\n\n\n<p>Auch hier gibt es nicht viel Forschung in Bezug auf eine bestimmte Makrodi\u00e4t und ihre Wirksamkeit f\u00fcr Gewichtsverlust, Gewichtskontrolle oder glyk\u00e4mische Indexkontrolle. Einige Leute argumentieren auch, dass es keine spezifische Makrodi\u00e4t gibt, da die Di\u00e4t auf der Idee basiert, dass Makros einstellbar sind.<\/p>\n\n\n\n<p>Eine Kohlenhydratarme Keto-Di\u00e4t und eine fettarme Di\u00e4t sind zwei Makro-Ans\u00e4tze mit sehr unterschiedlich aussehenden t\u00e4glichen Ern\u00e4hrungspl\u00e4nen.<\/p>\n\n\n\n<p>Ein Ern\u00e4hrungsberater kann mit Ihnen zusammenarbeiten, um festzustellen, was ein gutes Verh\u00e4ltnis von Makros f\u00fcr Ihre Gesundheitsziele sein kann.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.acefitness.org\/education-and-resources\/professional\/expert-articles\/5904\/how-to-determine-the-best-macronutrient-ratio-for-your-goals\" target=\"_blank\" rel=\"noreferrer noopener\">Einige Gesundheitsexperten<\/a>&nbsp;k\u00f6nnen sich f\u00fcr einen makrobasierten Ansatz f\u00fcr Di\u00e4ten einsetzen, da er bestimmte Lebensmittel aus Ihrer Ern\u00e4hrung nicht einschr\u00e4nkt. Kein Essen ist notwendigerweise verboten &#8211; es sollte nur in die Makroprozents\u00e4tze passen, die Sie essen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wann Sie mit einem Profi sprechen sollten<\/h2>\n\n\n\n<p>Wenn Sie den makrosen Ansatz ausprobiert haben, der in den Ern\u00e4hrungsrichtlinien f\u00fcr Amerikaner beschrieben ist, ohne die gew\u00fcnschten Ergebnisse zu erzielen, ist es m\u00f6glicherweise an der Zeit, mit einem Ern\u00e4hrungsberater oder Ihrem Arzt zu sprechen.<\/p>\n\n\n\n<p>Ein Ern\u00e4hrungsberater oder Ern\u00e4hrungsexperte kann empfehlen, Ihre Makron\u00e4hrstoffanteile basierend auf Ihrer allgemeinen Gesundheit und Ihren Ern\u00e4hrungszielen anzupassen.<\/p>\n\n\n\n<p>Stellen Sie sicher, dass Sie Ihrem neuen Ansatz Zeit zum Arbeiten geben, normalerweise etwa 2 bis 3 Monate, bevor Sie entscheiden, dass Sie Ihre Prozents\u00e4tze erneut \u00e4ndern m\u00fcssen.<\/p>\n\n\n\n<p>Ein Ern\u00e4hrungsberater oder Ern\u00e4hrungsexperte kann auch mit Ihnen sprechen, um sicherzustellen, dass Ihre Ziele realistisch sind und Ihr Ern\u00e4hrungsansatz sicher ist. Sie m\u00f6chten eine gesunde Ern\u00e4hrung und eine ausgewogene Ern\u00e4hrung betonen, um Ihre Ziele und k\u00f6rperlichen Bed\u00fcrfnisse zu erf\u00fcllen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Das Fazit<\/h2>\n\n\n\n<p>Makron\u00e4hrstoffe und Mikron\u00e4hrstoffe sind in Ihrer t\u00e4glichen Ern\u00e4hrung vorhanden. Manche Menschen verwenden Makron\u00e4hrstoffz\u00e4hlung, um ihre Nahrungsaufnahme zu steuern. Es gibt heute viele Di\u00e4ten, die einen Makroz\u00e4hlansatz verwenden, aber es gibt nicht viel Forschung \u00fcber das Z\u00e4hlen von Makros.<\/p>\n\n\n\n<p>Wenn Sie nicht sicher sind, wo Sie anfangen sollen, sprechen Sie mit Ihrem Arzt oder einem registrierten Ern\u00e4hrungsberater.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Makron\u00e4hrstoffe und Mikron\u00e4hrstoffe sind Kategorien, die Ern\u00e4hrungsberater und Ern\u00e4hrungsexperten verwenden k\u00f6nnen, um sich auf Ihre Ern\u00e4hrung zu beziehen. Makron\u00e4hrstoffe sind [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15056,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[251,19],"tags":[],"class_list":["post-15050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learn","category-nutrition"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"de","enabled_languages":["en","es","de","fr","ru","hi","ar","tr","it","pt","na"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"na":{"title":false,"content":false,"excerpt":false}}},"featured_img":"https:\/\/cdn.fitolympia.com\/file\/olympia-cdn\/wp-content\/uploads\/2021\/08\/macro.jpg","categories_details":[{"id":251,"name":"Learn","count":76,"parent":0},{"id":19,"name":"Nutrition","count":204,"parent":0}],"tags_details":[],"comment_count":0,"author_name":"Staff","author_img":"https:\/\/secure.gravatar.com\/avatar\/0770ff71d5267ad67c1cefbf36008dc2a2753c332616ff451380094010b0d281?s=96&d=mm&r=g","post_views":7599,"_links":{"self":[{"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/posts\/15050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/comments?post=15050"}],"version-history":[{"count":12,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/posts\/15050\/revisions"}],"predecessor-version":[{"id":15113,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/posts\/15050\/revisions\/15113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/media\/15056"}],"wp:attachment":[{"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/media?parent=15050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/categories?post=15050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fitolympia.com\/de\/wp-json\/wp\/v2\/tags?post=15050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}